{"id":10872,"date":"2026-04-16T07:14:08","date_gmt":"2026-04-16T05:14:08","guid":{"rendered":"https:\/\/beta.est-kl.com\/?p=10872"},"modified":"2026-07-07T09:19:27","modified_gmt":"2026-07-07T07:19:27","slug":"primex-22","status":"publish","type":"post","link":"https:\/\/www.est-kl.com\/es\/primex-22\/","title":{"rendered":"PrimeX\u00a022"},"content":{"rendered":"\n<div class=\"uagb-position__sticky wp-block-uagb-container uagb-layout-flex uagb-block-c37632dd alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-8160c408\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-b39dc514\"><h2 class=\"uagb-heading-text\">Prime<sup class=\"\">x<\/sup>&nbsp;22<\/h2><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-57b573d8\">\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-efb600c6\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-6c86d97c wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"https:\/\/www.est-kl.com\/es\/primex-22\/\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">In Depth<\/div><span class=\"uagb-button__icon uagb-button__icon-position-after\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 384 512\" aria-hidden=\"true\" focussable=\"false\"><path d=\"M192 384c-8.188 0-16.38-3.125-22.62-9.375l-160-160c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0L192 306.8l137.4-137.4c12.5-12.5 32.75-12.5 45.25 0s12.5 32.75 0 45.25l-160 160C208.4 380.9 200.2 384 192 384z\"><\/path><\/svg><\/span><\/a><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-8368e105 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"https:\/\/www.est-kl.com\/es\/primex-22-specs\/\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Specs<\/div><span class=\"uagb-button__icon uagb-button__icon-position-after\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 384 512\" aria-hidden=\"true\" focussable=\"false\"><path d=\"M192 384c-8.188 0-16.38-3.125-22.62-9.375l-160-160c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0L192 306.8l137.4-137.4c12.5-12.5 32.75-12.5 45.25 0s12.5 32.75 0 45.25l-160 160C208.4 380.9 200.2 384 192 384z\"><\/path><\/svg><\/span><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-217fd5a5 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-layout-grid uagb-block-49ad00df\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-2a25eb4d\"><h1 class=\"uagb-heading-text\">Prime<sup class=\"\">x<\/sup>&nbsp;22<\/h1><div class=\"uagb-separator\"><\/div><p class=\"uagb-desc-text\">The perfect blend of range, speed, and FOV.&nbsp;Edge-to-edge coverage while delivering stunning camera-to-marker range and 3D accuracy.<\/p><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-01a5ec31 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-98b90e67\">\n<div class=\"uagb-block-24eed835 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top \"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h1 class=\"uagb-ifb-title\"><strong class=\"\"><strong class=\"\">2.2<\/strong> MP<\/strong><\/h1><\/div><p class=\"uagb-ifb-desc\">resolution<\/p><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-58da930d\">\n<div class=\"uagb-block-f79d1186 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top \"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h1 class=\"uagb-ifb-title\">+\/- 0.2 mm<\/h1><\/div><p class=\"uagb-ifb-desc\">3D accuracy<sup><a href=\"#Footnote1\">1<\/a><\/sup><\/p><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-39ee6f6a\">\n<div class=\"uagb-block-4ab4d9d6 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top \"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h1 class=\"uagb-ifb-title\"><strong class=\"\">360 FPS<\/strong><\/h1><\/div><p class=\"uagb-ifb-desc\">native frame rate<\/p><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-a2f6c5e0\">\n<div class=\"uagb-block-32bcbeda uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top \"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h1 class=\"uagb-ifb-title\"><strong class=\"\">500+FPS<\/strong><\/h1><\/div><p class=\"uagb-ifb-desc\">max frame rate<sup><a href=\"#Footnote2\">2<\/a><\/sup><\/p><\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-grid uagb-block-80b095e0 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-5b5f2cd6\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-341a0dd6\"><h4 class=\"uagb-heading-text\">Prime<sup class=\"\">x<\/sup>&nbsp;Equals Precision.<\/h4><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">In-house designed low distortion lenses and true 10-bit grayscale depth reduces quantization noise and improves precision\u2014resulting in perfectly crisp and beautiful images, better centroids and better 3D accuracy.&nbsp;<strong class=\"\">Megapixels matter, but image quality matters more.<\/strong><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-0b1e3dc1\"><\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-grid uagb-block-863cfced alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-c7d62716\"><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-e7f3e310\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-d402941c\"><h4 class=\"uagb-heading-text\">Intuitive &amp; Elegant Design<\/h4><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">In designing the Prime<sup class=\"\">x<\/sup>&nbsp;series, OptiTrack considered the complete lifetime of a motion capture camera\u2014from unboxing to setup, capture, and teardown. Each process is elegantly accommodated with a nod to simplicity and usability.<\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-grid uagb-block-ce0a037a alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-3ae92481\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-260b1d97\"><h4 class=\"uagb-heading-text\">On-Camera Status Indicator<\/h4><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Prime<sup class=\"\">x<\/sup>&nbsp;cameras can keep users informed with definable color LED indicator rings surrounding the lens. Recording a performance? Everyone on set knows the system is recording. Select a camera? It instantly changes color. Have your own idea? Simple software controls help you make it so.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-9f65af31\"><div class=\"uagb-container__video-wrap\"><video autoplay loop muted playsinline><source src=\"https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/05\/primex22-color-ring-web.mp4\" type=\"video\/mp4\"\/><\/video><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-grid uagb-block-eb5bd218 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-42748acf\"><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-a5cf6412\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-f2e2013f\"><h4 class=\"uagb-heading-text\">\u201cFast Glass\u201d Lens Engineering<\/h4><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">OptiTrack custom designs their own super low distortion, \u201cfast glass\u201d lenses for optimal marker tracking. The Prime<sup class=\"\">x<\/sup>&nbsp;22\u2019s lenses feature a wide-band anti-reflective coating for greater light transmission, larger volumes, and more precision 3D data.<\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-grid uagb-block-ba971622 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-eef5b719\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3cf69d08\"><h4 class=\"uagb-heading-text\">Maximize Volume Size in Small Spaces<\/h4><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Prime<sup class=\"\">x<\/sup>&nbsp;22&nbsp;boasts a ultra-wide angle format and impressive range\u2014two features that do not co-exist in any other brand of motion capture camera. It delivers impressive capture volumes with edge to edge coverage in labs and studios under 50\u2019, and much larger measurement areas with overhead camera setups.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-5074e906\"><\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-grid uagb-block-4a753c21 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-4d6e79c8\"><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-851a34f4\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-a397766d\"><h4 class=\"uagb-heading-text\">Powerful On-Board Image Processing<\/h4><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">All OptiTrack cameras feature integrated image processing. The algorithms which identify markers and marker centers, and the sequence of data delivery are important steps to achieve both world leading accuracy and low latency.<\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-grid uagb-block-a77cae6b alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-eaf03854\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-6e502311\"><h4 class=\"uagb-heading-text\">High Frame-Rate Capture<\/h4><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">The Prime<sup class=\"\">x<\/sup>&nbsp;22\u2019s 360 FPS capture rate and image stopping global shutter can be used when your application requires Prime Series precision for movement speeds above 150mph.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-75ab9cfa\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-18c6690d\"><h1 class=\"uagb-heading-text\"><strong>360FPS<\/strong><\/h1><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-grid uagb-block-b5dc6176 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-25ed64b4\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-09816bf8\"><h4 class=\"uagb-heading-text\">Track Anything and Everything<\/h4><\/div>\n\n\n<div class=\"wp-block-uagb-faq uagb-faq__outer-wrap uagb-block-b98a8859 uagb-faq-icon-row uagb-faq-layout-accordion uagb-faq-expand-first-true uagb-faq-inactive-other-true uagb-faq__wrap uagb-buttons-layout-wrap uagb-faq-equal-height     \" data-faqtoggle=\"true\" role=\"tablist\"><div class=\"wp-block-uagb-faq-child uagb-faq-child__outer-wrap uagb-faq-item uagb-block-2b9904be \" role=\"tab\" tabindex=\"0\"><div class=\"uagb-faq-questions-button uagb-faq-questions\">\t\t\t<span class=\"uagb-icon uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 448 512\"><path d=\"M432 256c0 17.69-14.33 32.01-32 32.01H256v144c0 17.69-14.33 31.99-32 31.99s-32-14.3-32-31.99v-144H48c-17.67 0-32-14.32-32-32.01s14.33-31.99 32-31.99H192v-144c0-17.69 14.33-32.01 32-32.01s32 14.32 32 32.01v144h144C417.7 224 432 238.3 432 256z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"uagb-icon-active uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 448 512\"><path d=\"M400 288h-352c-17.69 0-32-14.32-32-32.01s14.31-31.99 32-31.99h352c17.69 0 32 14.3 32 31.99S417.7 288 400 288z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t<span class=\"uagb-question\"><strong>Track with Retroreflective Markers<\/strong><\/span><\/div><div class=\"uagb-faq-content\"><p>OptiTrack&#8217;s foundation. Retroreflective passive markers, illuminated by the cameras themselves, deliver the sub-millimeter accuracy that has defined motion capture for decades. From character animation to biomechanics to elite sports analysis, marker-based tracking remains the gold standard for capturing complex human and object motion with absolute precision.\u00a0<\/p><\/div><\/div><div class=\"wp-block-uagb-faq-child uagb-faq-child__outer-wrap uagb-faq-item uagb-block-7ec7674e \" role=\"tab\" tabindex=\"0\"><div class=\"uagb-faq-questions-button uagb-faq-questions\">\t\t\t<span class=\"uagb-icon uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 448 512\"><path d=\"M432 256c0 17.69-14.33 32.01-32 32.01H256v144c0 17.69-14.33 31.99-32 31.99s-32-14.3-32-31.99v-144H48c-17.67 0-32-14.32-32-32.01s14.33-31.99 32-31.99H192v-144c0-17.69 14.33-32.01 32-32.01s32 14.32 32 32.01v144h144C417.7 224 432 238.3 432 256z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"uagb-icon-active uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 448 512\"><path d=\"M400 288h-352c-17.69 0-32-14.32-32-32.01s14.31-31.99 32-31.99h352c17.69 0 32 14.3 32 31.99S417.7 288 400 288z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t<span class=\"uagb-question\"><strong>ActiveIO: Next Generation Active Tracking<\/strong><\/span><\/div><div class=\"uagb-faq-content\"><p>ActiveIO turns every marker into an intelligent, identifiable device \u2014 combining real-time identification, IMU sensor fusion, and extended range. Built for volumes where identical objects need unique identities, where GPIO inputs feed live data into Motive, and where tracking has to work the first time, every time.\u00a0<a href=\"https:\/\/www.optitrack.com\/activeio\"><\/a><\/p><\/div><\/div><div class=\"wp-block-uagb-faq-child uagb-faq-child__outer-wrap uagb-faq-item uagb-block-1c430da1 \" role=\"tab\" tabindex=\"0\"><div class=\"uagb-faq-questions-button uagb-faq-questions\">\t\t\t<span class=\"uagb-icon uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 448 512\"><path d=\"M432 256c0 17.69-14.33 32.01-32 32.01H256v144c0 17.69-14.33 31.99-32 31.99s-32-14.3-32-31.99v-144H48c-17.67 0-32-14.32-32-32.01s14.33-31.99 32-31.99H192v-144c0-17.69 14.33-32.01 32-32.01s32 14.32 32 32.01v144h144C417.7 224 432 238.3 432 256z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"uagb-icon-active uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 448 512\"><path d=\"M400 288h-352c-17.69 0-32-14.32-32-32.01s14.31-31.99 32-31.99h352c17.69 0 32 14.3 32 31.99S417.7 288 400 288z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t<span class=\"uagb-question\"><strong>Markerless &amp; Duplex Mode<\/strong><\/span><\/div><div class=\"uagb-faq-content\"><p>For subjects where suits and markers aren&#8217;t practical, OptiTrack supports markerless tracking \u2014 capturing natural human movement without any physical setup on the talent. With Duplex Mode and exclusive to OptiTrack, marker-based and markerless video capture can run simultaneously on the same camera system, so a single session serves both precision and flexibility needs.\u00a0<a href=\"https:\/\/www.optitrack.com\/duplexmode\"><\/a><a href=\"https:\/\/www.optitrack.com\/activeio\"><\/a><\/p><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-52483083\"><\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-grid uagb-block-2bcb69f4 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-46d3c6b5\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-8f9b2c3a\"><h4 class=\"uagb-heading-text\">Easy Set-Up<\/h4><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Aim assist and easily accessed lens controls make the Prime<sup class=\"\">x<\/sup>&nbsp;22&nbsp;fast and easy to set up.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-489a6b22\"><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-7f5140e3\"><h2 class=\"uagb-heading-text\">Prime<sup class=\"\">x<\/sup>&nbsp;is Feature Packed<\/h2><div class=\"uagb-separator\"><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-grid uagb-block-acda9497 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-9beaa52c\"><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-249a2b37\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-f129f270\"><h4 class=\"uagb-heading-text\">Full Resolution Grayscale Reference Video<\/h4><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">All Prime<sup class=\"\">x<\/sup>&nbsp;cameras can be used as a reference video source &#8211; with synchronized, calibrated overlay. Deliver and\/or record full resolution, full frame rate video with 3D overlay of markers, rigid bodies, skeletons, etc.<\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-grid uagb-block-5e6af294 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-b12c1033\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-85d0c948\"><h4 class=\"uagb-heading-text\">OEM &amp; Computer Vision Integration<\/h4><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Incorporate Prime<sup class=\"\">x<\/sup>&nbsp;cameras into OEM tracking or computer vision applications via the free&nbsp;SDK, a C\/C++ interface for control of and access to raw camera frames, image processing modes, camera settings, 2D object data, camera synchronization and all 3D data.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-f8bac439\"><\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-grid uagb-block-c5586b9c alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-61226197\"><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-5487f77b\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-5239e430\"><h4 class=\"uagb-heading-text\">Full Resolution Grayscale Reference Video<\/h4><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">With the eSync 2, cameras sync to nearly any source, including Genlock and SMPTE Time Code, for precise, flexible hardware synchronization. Trigger force plates, EMGs, and DAQs, or manage events through inputs and software commands, with full customization available via OptiTrack\u2019s free, open SDK.<\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-grid uagb-block-d0d3b0df alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-573db6ef\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-d153fd52\"><h4 class=\"uagb-heading-text\">Tracks Passive and Active Markers<\/h4><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">With positional errors less than +\/-0.15mm and rotational errors less than 0.5 degrees. For some tracking applications, customers find benefit in using a combination of active and passive markers.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-d9da6336\"><\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-grid uagb-block-9ee31919 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-a0f51320\"><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-3a3cf7db\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-e9ba948a\"><h4 class=\"uagb-heading-text\">Mix and Match Cameras<\/h4><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">OptiTrack cameras work together seamlessly to build the perfect motion capture system for any use case.<\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-grid uagb-block-ad6b2a76 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-2e04eb07\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-7fef2a0e\"><h4 class=\"uagb-heading-text\">Zero Drift. Pure Precision.<\/h4><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Motive calibrates automatically and continuously with data collected during normal use of the system. No longer does your calibration degrade over time with changing temperatures or challenging building movement\u2014it is always a \u201cfresh\u201d calibration.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-50af0eb4\"><div class=\"uagb-container__video-wrap\"><video autoplay loop muted playsinline><source src=\"https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/04\/continuous-calibration-web.mp4\" type=\"video\/mp4\"\/><\/video><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-grid uagb-block-cd025ccc alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-faaef517\"><div class=\"uagb-container__video-wrap\"><video autoplay loop muted playsinline><source src=\"https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/05\/what-is-motive-web-2x.mp4\" type=\"video\/mp4\"\/><\/video><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-2946affe\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-a30d811c\"><h4 class=\"uagb-heading-text\">Motive is behind every seamless workflow<\/h4><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">OptiTrack\u2019s Motive software delivers speed, precision, and ease of use, streamlining everything from calibration to real-time streaming, while tools like Aim Assist and auto-masking make even large system setups simple for one person.<\/p>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-9fda86f2\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-867181e8 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"https:\/\/www.est-kl.com\/es\/motive\/\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">About Motive<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div id=\"Footnote1\" class=\"wp-block-uagb-container uagb-block-46e52077 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-03d0b952\">\n<p class=\"wp-block-paragraph\"><sup>1.<\/sup><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-8bfd2a35\">\n<p class=\"wp-block-paragraph\"><sup>3D accuracy referenced is typical for a 30&#8217;\u00d730&#8242; (9m\u00d79m) tracking area. Range is estimated using a 14 mm marker with cameras at an exposure of 800, gain of 6, and the lowest f-stop. <\/sup><\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<div id=\"Footnote2\" class=\"wp-block-uagb-container uagb-block-c2a6af6f alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-9ad863ad\">\n<p class=\"wp-block-paragraph\"><sup>2.<\/sup><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-03e85a84\">\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th class=\"has-text-align-center\" data-align=\"center\"><sup><strong>Frame Rate<\/strong><\/sup><\/th><th class=\"has-text-align-center\" data-align=\"center\"><strong><sup>Resolution<\/sup><\/strong><\/th><th class=\"has-text-align-center\" data-align=\"center\"><sup><strong>FOV (standard 6.8mm lens)<\/strong><\/sup><\/th><\/tr><\/thead><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><sup>360 fps <\/sup><\/td><td class=\"has-text-align-center\" data-align=\"center\"><sup>2048&#215;1088<\/sup><\/td><td class=\"has-text-align-center\" data-align=\"center\"><sup>79\u00b0\u00d749\u00b0<\/sup><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><sup>500 fps<\/sup><\/td><td class=\"has-text-align-center\" data-align=\"center\"><sup>2048&#215;776<\/sup><\/td><td class=\"has-text-align-center\" data-align=\"center\"><sup>79\u00b0\u00d735\u00b0<\/sup><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><sup>1000 fps<\/sup><\/td><td class=\"has-text-align-center\" data-align=\"center\"><sup>2048&#215;384<\/sup><\/td><td class=\"has-text-align-center\" data-align=\"center\"><sup>79\u00b0\u00d718\u00b0<\/sup><\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-33209cc4 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-87a11183\"><h2 class=\"uagb-heading-text\">More Information<\/h2><div class=\"uagb-separator\"><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-5f32531b alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-09341d66\">\n<div class=\"wp-block-uagb-container uagb-block-c98f029a\">\n<div class=\"uagb-block-15fc2204 uagb-infobox__content-wrap  uagb-infobox_cta-type-all  uagb-infobox-icon-above-title uagb-infobox-image-valign-top \"><a href=\"\/wp-content\/uploads\/OptiTrack\/primex-family-spec-sheet-v13.pdf\" class=\"uagb-infobox-link-wrap uagb-infbox__link-to-all\" target=\"_blank\" aria-label=\"Infobox Link\" rel=\"noopener noreferrer\" onclick=\"return true;\"><\/a><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 384 512\"><path d=\"M88 304H80V256H88C101.3 256 112 266.7 112 280C112 293.3 101.3 304 88 304zM192 256H200C208.8 256 216 263.2 216 272V336C216 344.8 208.8 352 200 352H192V256zM224 0V128C224 145.7 238.3 160 256 160H384V448C384 483.3 355.3 512 320 512H64C28.65 512 0 483.3 0 448V64C0 28.65 28.65 0 64 0H224zM64 224C55.16 224 48 231.2 48 240V368C48 376.8 55.16 384 64 384C72.84 384 80 376.8 80 368V336H88C118.9 336 144 310.9 144 280C144 249.1 118.9 224 88 224H64zM160 368C160 376.8 167.2 384 176 384H200C226.5 384 248 362.5 248 336V272C248 245.5 226.5 224 200 224H176C167.2 224 160 231.2 160 240V368zM288 224C279.2 224 272 231.2 272 240V368C272 376.8 279.2 384 288 384C296.8 384 304 376.8 304 368V320H336C344.8 320 352 312.8 352 304C352 295.2 344.8 288 336 288H304V256H336C344.8 256 352 248.8 352 240C352 231.2 344.8 224 336 224H288zM256 0L384 128H256V0z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><h5 class=\"uagb-ifb-title\">Prime<sup>x<\/sup><br>Brochure<\/h5><\/div><div class=\"uagb-ifb-button-wrapper wp-block-button\"><\/div><\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-ae569a76\">\n<div class=\"wp-block-uagb-container uagb-block-d119f077\">\n<div class=\"uagb-block-4482f584 uagb-infobox__content-wrap  uagb-infobox_cta-type-all  uagb-infobox-icon-above-title uagb-infobox-image-valign-top \"><a href=\"\/wp-content\/uploads\/OptiTrack\/PrimeX-VersaX-Quick-Start-Guide-2026-03+1.pdf\" class=\"uagb-infobox-link-wrap uagb-infbox__link-to-all\" target=\"_blank\" aria-label=\"Infobox Link\" rel=\"noopener noreferrer\" onclick=\"return true;\"><\/a><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 384 512\"><path d=\"M88 304H80V256H88C101.3 256 112 266.7 112 280C112 293.3 101.3 304 88 304zM192 256H200C208.8 256 216 263.2 216 272V336C216 344.8 208.8 352 200 352H192V256zM224 0V128C224 145.7 238.3 160 256 160H384V448C384 483.3 355.3 512 320 512H64C28.65 512 0 483.3 0 448V64C0 28.65 28.65 0 64 0H224zM64 224C55.16 224 48 231.2 48 240V368C48 376.8 55.16 384 64 384C72.84 384 80 376.8 80 368V336H88C118.9 336 144 310.9 144 280C144 249.1 118.9 224 88 224H64zM160 368C160 376.8 167.2 384 176 384H200C226.5 384 248 362.5 248 336V272C248 245.5 226.5 224 200 224H176C167.2 224 160 231.2 160 240V368zM288 224C279.2 224 272 231.2 272 240V368C272 376.8 279.2 384 288 384C296.8 384 304 376.8 304 368V320H336C344.8 320 352 312.8 352 304C352 295.2 344.8 288 336 288H304V256H336C344.8 256 352 248.8 352 240C352 231.2 344.8 224 336 224H288zM256 0L384 128H256V0z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><h5 class=\"uagb-ifb-title\">Prime<sup>X<\/sup> <br>Quick Start Guide<\/h5><\/div><div class=\"uagb-ifb-button-wrapper wp-block-button\"><\/div><\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-81d10344\"><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-e6f7e635\"><\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-5ed88e67 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-13bf796f\"><h2 class=\"uagb-heading-text\">Related Products<\/h2><div class=\"uagb-separator\"><\/div><\/div>\n<\/div><\/div>\n\n\n<div class=\"wp-block-uagb-loop-builder uagb-block-560408fa      alignwide\" data-block_id=\"560408fa\"  style=\"\"><div id=\"uagb-block-queryid-0\" data-query-id=\"0\" class=\"uagb-loop-container uagb-block-5c866cf4     \" style=\"\"><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n<div class=\"wp-block-uagb-loop-wrapper\">\n<div class=\"wp-block-uagb-container uagb-block-0a6d8384 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-image uagb-block-157e55c8 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-src=\"https:\/\/beta.est-kl.de\/wp-content\/plugins\/spectra-pro\/assets\/images\/placeholder.png\" alt=\"Placeholder\" width=\"1200\" height=\"200\" title=\"\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/200;\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-dfc003ee\"><h5 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"post_permalink|post_permalink\" class=\"uag-pro-dynamic-content\" data-rich-text-format-boundary=\"true\">Loading\u2026<\/span><\/h5><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-17b75880\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">ARTTRACK5 is the next generation of the ARTTRACK camera family, the standard for immersive 3D applications in industry and research.<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-0f1b5f2d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-d6ad2265 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">More&#8230;<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n<div class=\"wp-block-uagb-loop-wrapper\">\n<div class=\"wp-block-uagb-container uagb-block-0a6d8384 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-image uagb-block-157e55c8 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-src=\"https:\/\/beta.est-kl.de\/wp-content\/plugins\/spectra-pro\/assets\/images\/placeholder.png\" alt=\"Placeholder\" width=\"1200\" height=\"200\" title=\"\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/200;\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-dfc003ee\"><h5 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"post_permalink|post_permalink\" class=\"uag-pro-dynamic-content\" data-rich-text-format-boundary=\"true\">Loading\u2026<\/span><\/h5><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-17b75880\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">ARTTRACK5 is the next generation of the ARTTRACK camera family, the standard for immersive 3D applications in industry and research.<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-0f1b5f2d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-d6ad2265 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">More&#8230;<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n<div class=\"wp-block-uagb-loop-wrapper\">\n<div class=\"wp-block-uagb-container uagb-block-0a6d8384 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-image uagb-block-157e55c8 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-src=\"https:\/\/beta.est-kl.de\/wp-content\/plugins\/spectra-pro\/assets\/images\/placeholder.png\" alt=\"Placeholder\" width=\"1200\" height=\"200\" title=\"\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/200;\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-dfc003ee\"><h5 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"post_permalink|post_permalink\" class=\"uag-pro-dynamic-content\" data-rich-text-format-boundary=\"true\">Loading\u2026<\/span><\/h5><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-17b75880\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">ARTTRACK5 is the next generation of the ARTTRACK camera family, the standard for immersive 3D applications in industry and research.<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-0f1b5f2d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-d6ad2265 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">More&#8230;<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n<div class=\"wp-block-uagb-loop-wrapper\">\n<div class=\"wp-block-uagb-container uagb-block-0a6d8384 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-image uagb-block-157e55c8 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-src=\"https:\/\/beta.est-kl.de\/wp-content\/plugins\/spectra-pro\/assets\/images\/placeholder.png\" alt=\"Placeholder\" width=\"1200\" height=\"200\" title=\"\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/200;\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-dfc003ee\"><h5 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"post_permalink|post_permalink\" class=\"uag-pro-dynamic-content\" data-rich-text-format-boundary=\"true\">Loading\u2026<\/span><\/h5><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-17b75880\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">ARTTRACK5 is the next generation of the ARTTRACK camera family, the standard for immersive 3D applications in industry and research.<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-0f1b5f2d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-d6ad2265 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">More&#8230;<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n<div class=\"wp-block-uagb-loop-wrapper\">\n<div class=\"wp-block-uagb-container uagb-block-0a6d8384 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-image uagb-block-157e55c8 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-src=\"https:\/\/beta.est-kl.de\/wp-content\/plugins\/spectra-pro\/assets\/images\/placeholder.png\" alt=\"Placeholder\" width=\"1200\" height=\"200\" title=\"\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/200;\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-dfc003ee\"><h5 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"post_permalink|post_permalink\" class=\"uag-pro-dynamic-content\" data-rich-text-format-boundary=\"true\">Loading\u2026<\/span><\/h5><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-17b75880\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">ARTTRACK5 is the next generation of the ARTTRACK camera family, the standard for immersive 3D applications in industry and research.<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-0f1b5f2d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-d6ad2265 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">More&#8230;<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n<div class=\"wp-block-uagb-loop-wrapper\">\n<div class=\"wp-block-uagb-container uagb-block-0a6d8384 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-image uagb-block-157e55c8 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-src=\"https:\/\/beta.est-kl.de\/wp-content\/plugins\/spectra-pro\/assets\/images\/placeholder.png\" alt=\"Placeholder\" width=\"1200\" height=\"200\" title=\"\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/200;\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-dfc003ee\"><h5 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"post_permalink|post_permalink\" class=\"uag-pro-dynamic-content\" data-rich-text-format-boundary=\"true\">Loading\u2026<\/span><\/h5><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-17b75880\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">ARTTRACK5 is the next generation of the ARTTRACK camera family, the standard for immersive 3D applications in industry and research.<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-0f1b5f2d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-d6ad2265 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">More&#8230;<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n<div class=\"wp-block-uagb-loop-wrapper\">\n<div class=\"wp-block-uagb-container uagb-block-0a6d8384 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-image uagb-block-157e55c8 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-src=\"https:\/\/beta.est-kl.de\/wp-content\/plugins\/spectra-pro\/assets\/images\/placeholder.png\" alt=\"Placeholder\" width=\"1200\" height=\"200\" title=\"\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/200;\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-dfc003ee\"><h5 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"post_permalink|post_permalink\" class=\"uag-pro-dynamic-content\" data-rich-text-format-boundary=\"true\">Loading\u2026<\/span><\/h5><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-17b75880\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">ARTTRACK5 is the next generation of the ARTTRACK camera family, the standard for immersive 3D applications in industry and research.<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-0f1b5f2d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-d6ad2265 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">More&#8230;<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n<div class=\"wp-block-uagb-loop-wrapper\">\n<div class=\"wp-block-uagb-container uagb-block-0a6d8384 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-image uagb-block-157e55c8 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-src=\"https:\/\/beta.est-kl.de\/wp-content\/plugins\/spectra-pro\/assets\/images\/placeholder.png\" alt=\"Placeholder\" width=\"1200\" height=\"200\" title=\"\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/200;\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-dfc003ee\"><h5 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"post_permalink|post_permalink\" class=\"uag-pro-dynamic-content\" data-rich-text-format-boundary=\"true\">Loading\u2026<\/span><\/h5><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-17b75880\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">ARTTRACK5 is the next generation of the ARTTRACK camera family, the standard for immersive 3D applications in industry and research.<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-0f1b5f2d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-d6ad2265 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">More&#8230;<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n<div class=\"wp-block-uagb-loop-wrapper\">\n<div class=\"wp-block-uagb-container uagb-block-0a6d8384 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-image uagb-block-157e55c8 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-src=\"https:\/\/beta.est-kl.de\/wp-content\/plugins\/spectra-pro\/assets\/images\/placeholder.png\" alt=\"Placeholder\" width=\"1200\" height=\"200\" title=\"\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/200;\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-dfc003ee\"><h5 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"post_permalink|post_permalink\" class=\"uag-pro-dynamic-content\" data-rich-text-format-boundary=\"true\">Loading\u2026<\/span><\/h5><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-17b75880\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">ARTTRACK5 is the next generation of the ARTTRACK camera family, the standard for immersive 3D applications in industry and research.<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-0f1b5f2d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-d6ad2265 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">More&#8230;<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n<div class=\"wp-block-uagb-loop-wrapper\">\n<div class=\"wp-block-uagb-container uagb-block-0a6d8384 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-image uagb-block-157e55c8 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-src=\"https:\/\/beta.est-kl.de\/wp-content\/plugins\/spectra-pro\/assets\/images\/placeholder.png\" alt=\"Placeholder\" width=\"1200\" height=\"200\" title=\"\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/200;\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-dfc003ee\"><h5 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"post_permalink|post_permalink\" class=\"uag-pro-dynamic-content\" data-rich-text-format-boundary=\"true\">Loading\u2026<\/span><\/h5><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-17b75880\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">ARTTRACK5 is the next generation of the ARTTRACK camera family, the standard for immersive 3D applications in industry and research.<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-0f1b5f2d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-d6ad2265 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">More&#8230;<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n<div class=\"wp-block-uagb-loop-wrapper\">\n<div class=\"wp-block-uagb-container uagb-block-0a6d8384 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-image uagb-block-157e55c8 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-src=\"https:\/\/beta.est-kl.de\/wp-content\/plugins\/spectra-pro\/assets\/images\/placeholder.png\" alt=\"Placeholder\" width=\"1200\" height=\"200\" title=\"\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/200;\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-dfc003ee\"><h5 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"post_permalink|post_permalink\" class=\"uag-pro-dynamic-content\" data-rich-text-format-boundary=\"true\">Loading\u2026<\/span><\/h5><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-17b75880\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">ARTTRACK5 is the next generation of the ARTTRACK camera family, the standard for immersive 3D applications in industry and research.<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-0f1b5f2d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-d6ad2265 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">More&#8230;<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n<div class=\"wp-block-uagb-loop-wrapper\">\n<div class=\"wp-block-uagb-container uagb-block-0a6d8384 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-image uagb-block-157e55c8 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-src=\"https:\/\/beta.est-kl.de\/wp-content\/plugins\/spectra-pro\/assets\/images\/placeholder.png\" alt=\"Placeholder\" width=\"1200\" height=\"200\" title=\"\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/200;\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-dfc003ee\"><h5 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"post_permalink|post_permalink\" class=\"uag-pro-dynamic-content\" data-rich-text-format-boundary=\"true\">Loading\u2026<\/span><\/h5><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-17b75880\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">ARTTRACK5 is the next generation of the ARTTRACK camera family, the standard for immersive 3D applications in industry and research.<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-0f1b5f2d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-d6ad2265 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">More&#8230;<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n<div class=\"wp-block-uagb-loop-wrapper\">\n<div class=\"wp-block-uagb-container uagb-block-0a6d8384 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-image uagb-block-157e55c8 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-src=\"https:\/\/beta.est-kl.de\/wp-content\/plugins\/spectra-pro\/assets\/images\/placeholder.png\" alt=\"Placeholder\" width=\"1200\" height=\"200\" title=\"\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/200;\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-dfc003ee\"><h5 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"post_permalink|post_permalink\" class=\"uag-pro-dynamic-content\" data-rich-text-format-boundary=\"true\">Loading\u2026<\/span><\/h5><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-17b75880\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">ARTTRACK5 is the next generation of the ARTTRACK camera family, the standard for immersive 3D applications in industry and research.<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-0f1b5f2d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-d6ad2265 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">More&#8230;<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n<div class=\"wp-block-uagb-loop-wrapper\">\n<div class=\"wp-block-uagb-container uagb-block-0a6d8384 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-image uagb-block-157e55c8 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-src=\"https:\/\/beta.est-kl.de\/wp-content\/plugins\/spectra-pro\/assets\/images\/placeholder.png\" alt=\"Placeholder\" width=\"1200\" height=\"200\" title=\"\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/200;\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-dfc003ee\"><h5 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"post_permalink|post_permalink\" class=\"uag-pro-dynamic-content\" data-rich-text-format-boundary=\"true\">Loading\u2026<\/span><\/h5><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-17b75880\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">ARTTRACK5 is the next generation of the ARTTRACK camera family, the standard for immersive 3D applications in industry and research.<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-0f1b5f2d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-d6ad2265 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">More&#8230;<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n<div class=\"wp-block-uagb-loop-wrapper\">\n<div class=\"wp-block-uagb-container uagb-block-0a6d8384 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-image uagb-block-157e55c8 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-src=\"https:\/\/beta.est-kl.de\/wp-content\/plugins\/spectra-pro\/assets\/images\/placeholder.png\" alt=\"Placeholder\" width=\"1200\" height=\"200\" title=\"\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/200;\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-dfc003ee\"><h5 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"post_permalink|post_permalink\" class=\"uag-pro-dynamic-content\" data-rich-text-format-boundary=\"true\">Loading\u2026<\/span><\/h5><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-17b75880\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">ARTTRACK5 is the next generation of the ARTTRACK camera family, the standard for immersive 3D applications in industry and research.<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-0f1b5f2d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-d6ad2265 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">More&#8230;<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n<div class=\"wp-block-uagb-loop-wrapper\">\n<div class=\"wp-block-uagb-container uagb-block-0a6d8384 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-image uagb-block-157e55c8 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-src=\"https:\/\/beta.est-kl.de\/wp-content\/plugins\/spectra-pro\/assets\/images\/placeholder.png\" alt=\"Placeholder\" width=\"1200\" height=\"200\" title=\"\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/200;\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-dfc003ee\"><h5 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"post_permalink|post_permalink\" class=\"uag-pro-dynamic-content\" data-rich-text-format-boundary=\"true\">Loading\u2026<\/span><\/h5><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-17b75880\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">ARTTRACK5 is the next generation of the ARTTRACK camera family, the standard for immersive 3D applications in industry and research.<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-0f1b5f2d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-d6ad2265 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">More&#8230;<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n<div class=\"wp-block-uagb-loop-wrapper\">\n<div class=\"wp-block-uagb-container uagb-block-0a6d8384 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-image uagb-block-157e55c8 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-src=\"https:\/\/beta.est-kl.de\/wp-content\/plugins\/spectra-pro\/assets\/images\/placeholder.png\" alt=\"Placeholder\" width=\"1200\" height=\"200\" title=\"\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/200;\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-dfc003ee\"><h5 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"post_permalink|post_permalink\" class=\"uag-pro-dynamic-content\" data-rich-text-format-boundary=\"true\">Loading\u2026<\/span><\/h5><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-17b75880\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">ARTTRACK5 is the next generation of the ARTTRACK camera family, the standard for immersive 3D applications in industry and research.<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-0f1b5f2d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-d6ad2265 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">More&#8230;<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n<div class=\"wp-block-uagb-loop-wrapper\">\n<div class=\"wp-block-uagb-container uagb-block-0a6d8384 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-image uagb-block-157e55c8 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-src=\"https:\/\/beta.est-kl.de\/wp-content\/plugins\/spectra-pro\/assets\/images\/placeholder.png\" alt=\"Placeholder\" width=\"1200\" height=\"200\" title=\"\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/200;\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-dfc003ee\"><h5 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"post_permalink|post_permalink\" class=\"uag-pro-dynamic-content\" data-rich-text-format-boundary=\"true\">Loading\u2026<\/span><\/h5><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-17b75880\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">ARTTRACK5 is the next generation of the ARTTRACK camera family, the standard for immersive 3D applications in industry and research.<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-0f1b5f2d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-d6ad2265 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">More&#8230;<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n<div class=\"wp-block-uagb-loop-wrapper\">\n<div class=\"wp-block-uagb-container uagb-block-0a6d8384 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-image uagb-block-157e55c8 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-src=\"https:\/\/beta.est-kl.de\/wp-content\/plugins\/spectra-pro\/assets\/images\/placeholder.png\" alt=\"Placeholder\" width=\"1200\" height=\"200\" title=\"\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/200;\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-dfc003ee\"><h5 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"post_permalink|post_permalink\" class=\"uag-pro-dynamic-content\" data-rich-text-format-boundary=\"true\">Loading\u2026<\/span><\/h5><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-17b75880\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">ARTTRACK5 is the next generation of the ARTTRACK camera family, the standard for immersive 3D applications in industry and research.<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-0f1b5f2d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-d6ad2265 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">More&#8230;<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n<div class=\"wp-block-uagb-loop-wrapper\">\n<div class=\"wp-block-uagb-container uagb-block-0a6d8384 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-image uagb-block-157e55c8 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-src=\"https:\/\/beta.est-kl.de\/wp-content\/plugins\/spectra-pro\/assets\/images\/placeholder.png\" alt=\"Placeholder\" width=\"1200\" height=\"200\" title=\"\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/200;\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-dfc003ee\"><h5 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"post_permalink|post_permalink\" class=\"uag-pro-dynamic-content\" data-rich-text-format-boundary=\"true\">Loading\u2026<\/span><\/h5><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-17b75880\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">ARTTRACK5 is the next generation of the ARTTRACK camera family, the standard for immersive 3D applications in industry and research.<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-0f1b5f2d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-d6ad2265 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">More&#8230;<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n<div class=\"wp-block-uagb-loop-wrapper\">\n<div class=\"wp-block-uagb-container uagb-block-0a6d8384 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-image uagb-block-157e55c8 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-src=\"https:\/\/beta.est-kl.de\/wp-content\/plugins\/spectra-pro\/assets\/images\/placeholder.png\" alt=\"Placeholder\" width=\"1200\" height=\"200\" title=\"\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/200;\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-dfc003ee\"><h5 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"post_permalink|post_permalink\" class=\"uag-pro-dynamic-content\" data-rich-text-format-boundary=\"true\">Loading\u2026<\/span><\/h5><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-17b75880\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">ARTTRACK5 is the next generation of the ARTTRACK camera family, the standard for immersive 3D applications in industry and research.<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-0f1b5f2d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-d6ad2265 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">More&#8230;<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n<div class=\"wp-block-uagb-loop-wrapper\">\n<div class=\"wp-block-uagb-container uagb-block-0a6d8384 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-image uagb-block-157e55c8 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-src=\"https:\/\/beta.est-kl.de\/wp-content\/plugins\/spectra-pro\/assets\/images\/placeholder.png\" alt=\"Placeholder\" width=\"1200\" height=\"200\" title=\"\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/200;\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-dfc003ee\"><h5 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"post_permalink|post_permalink\" class=\"uag-pro-dynamic-content\" data-rich-text-format-boundary=\"true\">Loading\u2026<\/span><\/h5><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-17b75880\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">ARTTRACK5 is the next generation of the ARTTRACK camera family, the standard for immersive 3D applications in industry and research.<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-0f1b5f2d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-d6ad2265 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">More&#8230;<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n<div class=\"wp-block-uagb-loop-wrapper\">\n<div class=\"wp-block-uagb-container uagb-block-0a6d8384 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-image uagb-block-157e55c8 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-src=\"https:\/\/beta.est-kl.de\/wp-content\/plugins\/spectra-pro\/assets\/images\/placeholder.png\" alt=\"Placeholder\" width=\"1200\" height=\"200\" title=\"\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/200;\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-dfc003ee\"><h5 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"post_permalink|post_permalink\" class=\"uag-pro-dynamic-content\" data-rich-text-format-boundary=\"true\">Loading\u2026<\/span><\/h5><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-17b75880\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">ARTTRACK5 is the next generation of the ARTTRACK camera family, the standard for immersive 3D applications in industry and research.<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-0f1b5f2d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-d6ad2265 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">More&#8230;<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n<div class=\"wp-block-uagb-loop-wrapper\">\n<div class=\"wp-block-uagb-container uagb-block-0a6d8384 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-image uagb-block-157e55c8 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-src=\"https:\/\/beta.est-kl.de\/wp-content\/plugins\/spectra-pro\/assets\/images\/placeholder.png\" alt=\"Placeholder\" width=\"1200\" height=\"200\" title=\"\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/200;\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-dfc003ee\"><h5 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"post_permalink|post_permalink\" class=\"uag-pro-dynamic-content\" data-rich-text-format-boundary=\"true\">Loading\u2026<\/span><\/h5><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-17b75880\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">ARTTRACK5 is the next generation of the ARTTRACK camera family, the standard for immersive 3D applications in industry and research.<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-0f1b5f2d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-d6ad2265 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">More&#8230;<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n<div class=\"wp-block-uagb-loop-wrapper\">\n<div class=\"wp-block-uagb-container uagb-block-0a6d8384 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-image uagb-block-157e55c8 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-src=\"https:\/\/beta.est-kl.de\/wp-content\/plugins\/spectra-pro\/assets\/images\/placeholder.png\" alt=\"Placeholder\" width=\"1200\" height=\"200\" title=\"\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/200;\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-dfc003ee\"><h5 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"post_permalink|post_permalink\" class=\"uag-pro-dynamic-content\" data-rich-text-format-boundary=\"true\">Loading\u2026<\/span><\/h5><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-17b75880\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">ARTTRACK5 is the next generation of the ARTTRACK camera family, the standard for immersive 3D applications in industry and research.<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-0f1b5f2d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-d6ad2265 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">More&#8230;<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n<div class=\"wp-block-uagb-loop-wrapper\">\n<div class=\"wp-block-uagb-container uagb-block-0a6d8384 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-image uagb-block-157e55c8 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-src=\"https:\/\/beta.est-kl.de\/wp-content\/plugins\/spectra-pro\/assets\/images\/placeholder.png\" alt=\"Placeholder\" width=\"1200\" height=\"200\" title=\"\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/200;\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-dfc003ee\"><h5 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"post_permalink|post_permalink\" class=\"uag-pro-dynamic-content\" data-rich-text-format-boundary=\"true\">Loading\u2026<\/span><\/h5><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-17b75880\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">ARTTRACK5 is the next generation of the ARTTRACK camera family, the standard for immersive 3D applications in industry and research.<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-0f1b5f2d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-d6ad2265 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">More&#8230;<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n<div class=\"wp-block-uagb-loop-wrapper\">\n<div class=\"wp-block-uagb-container uagb-block-0a6d8384 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-image uagb-block-157e55c8 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-src=\"https:\/\/beta.est-kl.de\/wp-content\/plugins\/spectra-pro\/assets\/images\/placeholder.png\" alt=\"Placeholder\" width=\"1200\" height=\"200\" title=\"\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/200;\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-dfc003ee\"><h5 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"post_permalink|post_permalink\" class=\"uag-pro-dynamic-content\" data-rich-text-format-boundary=\"true\">Loading\u2026<\/span><\/h5><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-17b75880\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">ARTTRACK5 is the next generation of the ARTTRACK camera family, the standard for immersive 3D applications in industry and research.<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-0f1b5f2d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-d6ad2265 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">More&#8230;<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n<div class=\"wp-block-uagb-loop-wrapper\">\n<div class=\"wp-block-uagb-container uagb-block-0a6d8384 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-image uagb-block-157e55c8 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-src=\"https:\/\/beta.est-kl.de\/wp-content\/plugins\/spectra-pro\/assets\/images\/placeholder.png\" alt=\"Placeholder\" width=\"1200\" height=\"200\" title=\"\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/200;\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-dfc003ee\"><h5 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"post_permalink|post_permalink\" class=\"uag-pro-dynamic-content\" data-rich-text-format-boundary=\"true\">Loading\u2026<\/span><\/h5><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-17b75880\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">ARTTRACK5 is the next generation of the ARTTRACK camera family, the standard for immersive 3D applications in industry and research.<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-0f1b5f2d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-d6ad2265 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">More&#8230;<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n<div class=\"wp-block-uagb-loop-wrapper\">\n<div class=\"wp-block-uagb-container uagb-block-0a6d8384 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-image uagb-block-157e55c8 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-src=\"https:\/\/beta.est-kl.de\/wp-content\/plugins\/spectra-pro\/assets\/images\/placeholder.png\" alt=\"Placeholder\" width=\"1200\" height=\"200\" title=\"\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/200;\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-dfc003ee\"><h5 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"post_permalink|post_permalink\" class=\"uag-pro-dynamic-content\" data-rich-text-format-boundary=\"true\">Loading\u2026<\/span><\/h5><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-17b75880\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">ARTTRACK5 is the next generation of the ARTTRACK camera family, the standard for immersive 3D applications in industry and research.<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-0f1b5f2d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-d6ad2265 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">More&#8230;<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n<div class=\"wp-block-uagb-loop-wrapper\">\n<div class=\"wp-block-uagb-container uagb-block-0a6d8384 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-image uagb-block-157e55c8 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-src=\"https:\/\/beta.est-kl.de\/wp-content\/plugins\/spectra-pro\/assets\/images\/placeholder.png\" alt=\"Placeholder\" width=\"1200\" height=\"200\" title=\"\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/200;\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-dfc003ee\"><h5 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"post_permalink|post_permalink\" class=\"uag-pro-dynamic-content\" data-rich-text-format-boundary=\"true\">Loading\u2026<\/span><\/h5><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-17b75880\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">ARTTRACK5 is the next generation of the ARTTRACK camera family, the standard for immersive 3D applications in industry and research.<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-0f1b5f2d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-d6ad2265 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">More&#8230;<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n<div class=\"wp-block-uagb-loop-wrapper\">\n<div class=\"wp-block-uagb-container uagb-block-0a6d8384 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-image uagb-block-157e55c8 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-src=\"https:\/\/beta.est-kl.de\/wp-content\/plugins\/spectra-pro\/assets\/images\/placeholder.png\" alt=\"Placeholder\" width=\"1200\" height=\"200\" title=\"\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/200;\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-dfc003ee\"><h5 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"post_permalink|post_permalink\" class=\"uag-pro-dynamic-content\" data-rich-text-format-boundary=\"true\">Loading\u2026<\/span><\/h5><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-17b75880\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">ARTTRACK5 is the next generation of the ARTTRACK camera family, the standard for immersive 3D applications in industry and research.<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-0f1b5f2d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-d6ad2265 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">More&#8230;<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n<div class=\"wp-block-uagb-loop-wrapper\">\n<div class=\"wp-block-uagb-container uagb-block-0a6d8384 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-image uagb-block-157e55c8 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-src=\"https:\/\/beta.est-kl.de\/wp-content\/plugins\/spectra-pro\/assets\/images\/placeholder.png\" alt=\"Placeholder\" width=\"1200\" height=\"200\" title=\"\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/200;\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-dfc003ee\"><h5 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"post_permalink|post_permalink\" class=\"uag-pro-dynamic-content\" data-rich-text-format-boundary=\"true\">Loading\u2026<\/span><\/h5><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-17b75880\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">ARTTRACK5 is the next generation of the ARTTRACK camera family, the standard for immersive 3D applications in industry and research.<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-0f1b5f2d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-d6ad2265 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">More&#8230;<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n<div class=\"wp-block-uagb-loop-wrapper\">\n<div class=\"wp-block-uagb-container uagb-block-0a6d8384 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-image uagb-block-157e55c8 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-src=\"https:\/\/beta.est-kl.de\/wp-content\/plugins\/spectra-pro\/assets\/images\/placeholder.png\" alt=\"Placeholder\" width=\"1200\" height=\"200\" title=\"\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/200;\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-dfc003ee\"><h5 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"post_permalink|post_permalink\" class=\"uag-pro-dynamic-content\" data-rich-text-format-boundary=\"true\">Loading\u2026<\/span><\/h5><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-17b75880\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">ARTTRACK5 is the next generation of the ARTTRACK camera family, the standard for immersive 3D applications in industry and research.<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-0f1b5f2d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-d6ad2265 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">More&#8230;<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div><\/div><\/div>\n\n\n<div class=\"wp-block-uagb-container uagb-block-04b07a79 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-c874a272\"><div class=\"uagb-separator\"><\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Specifications and other information are subject to change without notice. All brand and product names are trademarks or registered trademarks of their respective holders. The information on this webpage is provided by the respective named manufacturer and is for general information purposes. These data constitute a concrete indication of properties and condition only if they are expressly indicated by EST or have been agreed upon as a condition in writing.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-87a8d82a alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-columns are-vertically-aligned-top is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-top is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-uagb-info-box uagb-block-1fff170c uagb-infobox__content-wrap  uagb-infobox-icon-left uagb-infobox-left uagb-infobox-stacked-tablet uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M285.6 444.1C279.8 458.3 264.8 466.3 249.8 463.4C234.8 460.4 223.1 447.3 223.1 432V256H47.1C32.71 256 19.55 245.2 16.6 230.2C13.65 215.2 21.73 200.2 35.88 194.4L387.9 50.38C399.8 45.5 413.5 48.26 422.6 57.37C431.7 66.49 434.5 80.19 429.6 92.12L285.6 444.1z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">Direcci\u00f3n:<\/h3><\/div><p class=\"uagb-ifb-desc\">Wilhelm-Raabe-Str. 6<br\/>67663 Kaiserslautern, Germany<\/p><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-top is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-uagb-info-box uagb-block-45a1a311 uagb-infobox__content-wrap  uagb-infobox-icon-left uagb-infobox-left uagb-infobox-stacked-tablet uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M464 64C490.5 64 512 85.49 512 112C512 127.1 504.9 141.3 492.8 150.4L275.2 313.6C263.8 322.1 248.2 322.1 236.8 313.6L19.2 150.4C7.113 141.3 0 127.1 0 112C0 85.49 21.49 64 48 64H464zM217.6 339.2C240.4 356.3 271.6 356.3 294.4 339.2L512 176V384C512 419.3 483.3 448 448 448H64C28.65 448 0 419.3 0 384V176L217.6 339.2z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">Correo electr\u00f3nico:<\/h3><\/div><p class=\"uagb-ifb-desc\">sales@est-kl.com<\/p><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-top is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-uagb-info-box uagb-block-19a3586d uagb-infobox__content-wrap  uagb-infobox-icon-left uagb-infobox-left uagb-infobox-stacked-tablet uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M256 512C114.6 512 0 397.4 0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256C512 397.4 397.4 512 256 512zM232 256C232 264 236 271.5 242.7 275.1L338.7 339.1C349.7 347.3 364.6 344.3 371.1 333.3C379.3 322.3 376.3 307.4 365.3 300L280 243.2V120C280 106.7 269.3 96 255.1 96C242.7 96 231.1 106.7 231.1 120L232 256z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">Horario de apertura:<\/h3><\/div><p class=\"uagb-ifb-desc\">Mon-Fri: 8:30 \u2013 17:30 CET<\/p><\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>The perfect blend of range, speed, and FOV. Edge-to-edge coverage while delivering stunning camera-to-marker range and 3D accuracy.<\/p>\n","protected":false},"author":1,"featured_media":14073,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":"[]"},"categories":[740],"tags":[67,68,474,794],"class_list":["post-10872","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-optitrack","tag-motion-tracking-es","tag-optical-tracking-es","tag-optitrack-es","tag-primex"],"spectra_custom_meta":{"_encloseme":["1"],"_icl_lang_duplicate_of":["10859"],"_thumbnail_id":["14073"],"_wp_old_slug":["arttrack5-2","at7-80-2","art-satellite-merger-3","art-markers-4","g6-mocapsuit-17","primex-13-2"],"copied_media_ids":["a:1:{i:0;i:0;}","a:1:{i:0;i:0;}","a:1:{i:0;i:0;}","a:1:{i:0;i:0;}","a:1:{i:0;i:0;}","a:1:{i:0;i:0;}","a:1:{i:0;i:0;}","a:1:{i:0;i:0;}","a:1:{i:0;i:0;}","a:1:{i:0;i:0;}","a:1:{i:0;i:0;}","a:1:{i:0;i:0;}","a:1:{i:0;i:0;}","a:1:{i:0;i:0;}","a:1:{i:0;i:0;}","a:1:{i:0;i:0;}","a:1:{i:0;i:0;}","a:1:{i:0;i:0;}","a:1:{i:0;i:0;}","a:1:{i:0;i:0;}"],"referenced_media_ids":["a:1:{i:0;i:14066;}","a:1:{i:0;i:14066;}","a:1:{i:0;i:14066;}","a:1:{i:0;i:14066;}","a:1:{i:0;i:14066;}","a:1:{i:0;i:14066;}","a:1:{i:0;i:14066;}","a:1:{i:0;i:14066;}","a:1:{i:0;i:14066;}","a:1:{i:0;i:14066;}","a:1:{i:0;i:14066;}","a:1:{i:0;i:14066;}","a:1:{i:0;i:14066;}","a:1:{i:0;i:14066;}","a:1:{i:0;i:14066;}","a:1:{i:0;i:14066;}","a:1:{i:0;i:14066;}","a:1:{i:0;i:14066;}","a:1:{i:0;i:14066;}","a:1:{i:0;i:14066;}"],"_wpml_word_count":["831"],"cmplz_hide_cookiebanner":[""],"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"_wpml_location_migration_done":["1"],"_oembed_5376c2619353739c7b2328713759a081":["<iframe title=\"ARTTRACK5 product video\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/5ap0tY4oIIQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>"],"_oembed_time_5376c2619353739c7b2328713759a081":["1701942082"],"_oembed_2abf571ed1069fdf1ff882324fdf5e71":["<iframe title=\"ARTTRACK5 product video\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/5ap0tY4oIIQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>"],"_oembed_time_2abf571ed1069fdf1ff882324fdf5e71":["1700558580"],"_uag_custom_page_level_css":[""],"ast-site-content-layout":["default"],"theme-transparent-header-meta":[""],"adv-header-id-meta":[""],"stick-header-meta":[""],"astra-migrate-meta-layouts":[""],"footnotes":["[]"],"_last_translation_edit_mode":["native-editor"],"_oembed_aa67a842ebefcbe5059e77d33eb3df80":["<iframe title=\"ARTTRACK5 product video\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/5ap0tY4oIIQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>"],"_oembed_time_aa67a842ebefcbe5059e77d33eb3df80":["1772528138"],"_genesis_description":["The perfect blend of range, speed, and FOV. Edge-to-edge coverage while delivering stunning camera-to-marker range and 3D accuracy."],"_social_image_url":["https:\/\/beta.est-kl.de\/wp-content\/uploads\/2024\/08\/cropped-AT7-80.vonrechts.gruen_.png"],"_social_image_id":["6100"],"_open_graph_title":["OptiTrack Primex 22 available from EST"],"_wpml_post_translation_editor_native":["yes"],"_oembed_bc2458ba3fadcf2b45bfe193022299bf":["<iframe title=\"AT7-80 premium tracking camera\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/C_WElLjmPEI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>"],"_oembed_time_bc2458ba3fadcf2b45bfe193022299bf":["1759323583"],"_oembed_135f134473b955c2bc19e87aa548f5ad":["<iframe title=\"AT7-80 premium tracking camera\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/C_WElLjmPEI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>"],"_oembed_time_135f134473b955c2bc19e87aa548f5ad":["1759323344"],"_genesis_title":["OptiTrack Primex 22 available from"],"_oembed_712738f527182a5477af962407395fce":["<iframe title=\"New SMARTTRACK3 \u2013 largest field of view of any compact tracking solution worldwide\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/rmFieJYXRJs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>"],"_oembed_time_712738f527182a5477af962407395fce":["1772528605"],"_oembed_bab89bbba9477a6118bbb25f68581f09":["<iframe title=\"New SMARTTRACK3 \u2013 largest field of view of any compact tracking solution worldwide\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/rmFieJYXRJs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>"],"_oembed_time_bab89bbba9477a6118bbb25f68581f09":["1772528733"],"_oembed_f08bb03e690a5f91a1e2160c590e89a4":["<iframe title=\"Flystick2+ - ART&#039;s new wireless interaction device for VR applications\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/wGlr3iGjT-c?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>"],"_oembed_time_f08bb03e690a5f91a1e2160c590e89a4":["1772530017"],"_oembed_fe0d470701575fabd19ec374ef78507d":["<iframe title=\"Flystick2+ - ART&#039;s new wireless interaction device for VR applications\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/wGlr3iGjT-c?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>"],"_oembed_time_fe0d470701575fabd19ec374ef78507d":["1772530063"],"_oembed_672732dea71b128162a6a326bf3760f2":["<iframe title=\"FINGERTRACKING2 Tactile\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/0xVli6V7odY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>"],"_oembed_time_672732dea71b128162a6a326bf3760f2":["1772532182"],"_oembed_501a6d3f04259a0ff8222213d4143586":["<iframe title=\"FINGERTRACKING2 Tactile\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/0xVli6V7odY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>"],"_oembed_time_501a6d3f04259a0ff8222213d4143586":["1772532103"],"_oembed_c977486bc7e5bb3b2f0d2a43ac9896f5":["<iframe title=\"Manus Prime II ART glove announcement\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/Br66ZB6ngVg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>"],"_oembed_time_c977486bc7e5bb3b2f0d2a43ac9896f5":["1772532175"],"_oembed_43dac133bf9e314ee9f0ea5bdc378340":["<iframe title=\"Manus Prime II ART glove announcement\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/Br66ZB6ngVg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>"],"_oembed_time_43dac133bf9e314ee9f0ea5bdc378340":["1772532192"],"_wp_old_date":["2026-03-03","2026-03-05","2026-04-07","2026-05-04"],"_uagb_previous_block_counts":["a:90:{s:21:\"uagb\/advanced-heading\";i:24;s:15:\"uagb\/blockquote\";i:0;s:12:\"uagb\/buttons\";i:3;s:18:\"uagb\/buttons-child\";i:4;s:19:\"uagb\/call-to-action\";i:0;s:15:\"uagb\/cf7-styler\";i:0;s:11:\"uagb\/column\";i:0;s:12:\"uagb\/columns\";i:0;s:14:\"uagb\/container\";i:74;s:21:\"uagb\/content-timeline\";i:0;s:27:\"uagb\/content-timeline-child\";i:0;s:14:\"uagb\/countdown\";i:0;s:12:\"uagb\/counter\";i:0;s:8:\"uagb\/faq\";i:1;s:14:\"uagb\/faq-child\";i:3;s:10:\"uagb\/forms\";i:0;s:17:\"uagb\/forms-accept\";i:0;s:19:\"uagb\/forms-checkbox\";i:0;s:15:\"uagb\/forms-date\";i:0;s:16:\"uagb\/forms-email\";i:0;s:17:\"uagb\/forms-hidden\";i:0;s:15:\"uagb\/forms-name\";i:0;s:16:\"uagb\/forms-phone\";i:0;s:16:\"uagb\/forms-radio\";i:0;s:17:\"uagb\/forms-select\";i:0;s:19:\"uagb\/forms-textarea\";i:0;s:17:\"uagb\/forms-toggle\";i:0;s:14:\"uagb\/forms-url\";i:0;s:14:\"uagb\/gf-styler\";i:0;s:15:\"uagb\/google-map\";i:0;s:11:\"uagb\/how-to\";i:0;s:16:\"uagb\/how-to-step\";i:0;s:9:\"uagb\/icon\";i:0;s:14:\"uagb\/icon-list\";i:0;s:20:\"uagb\/icon-list-child\";i:0;s:10:\"uagb\/image\";i:1;s:18:\"uagb\/image-gallery\";i:0;s:13:\"uagb\/info-box\";i:6;s:18:\"uagb\/inline-notice\";i:0;s:11:\"uagb\/lottie\";i:0;s:21:\"uagb\/marketing-button\";i:0;s:10:\"uagb\/modal\";i:0;s:18:\"uagb\/popup-builder\";i:0;s:16:\"uagb\/post-button\";i:0;s:18:\"uagb\/post-carousel\";i:0;s:17:\"uagb\/post-excerpt\";i:0;s:14:\"uagb\/post-grid\";i:0;s:15:\"uagb\/post-image\";i:0;s:17:\"uagb\/post-masonry\";i:0;s:14:\"uagb\/post-meta\";i:0;s:18:\"uagb\/post-taxonomy\";i:0;s:18:\"uagb\/post-timeline\";i:0;s:15:\"uagb\/post-title\";i:0;s:20:\"uagb\/restaurant-menu\";i:0;s:26:\"uagb\/restaurant-menu-child\";i:0;s:11:\"uagb\/review\";i:0;s:12:\"uagb\/section\";i:0;s:14:\"uagb\/separator\";i:0;s:11:\"uagb\/slider\";i:0;s:17:\"uagb\/slider-child\";i:0;s:17:\"uagb\/social-share\";i:0;s:23:\"uagb\/social-share-child\";i:0;s:16:\"uagb\/star-rating\";i:0;s:23:\"uagb\/sure-cart-checkout\";i:0;s:22:\"uagb\/sure-cart-product\";i:0;s:15:\"uagb\/sure-forms\";i:0;s:22:\"uagb\/table-of-contents\";i:0;s:9:\"uagb\/tabs\";i:0;s:15:\"uagb\/tabs-child\";i:0;s:18:\"uagb\/taxonomy-list\";i:0;s:9:\"uagb\/team\";i:0;s:16:\"uagb\/testimonial\";i:0;s:14:\"uagb\/wp-search\";i:0;s:19:\"uagb\/instagram-feed\";i:0;s:10:\"uagb\/login\";i:0;s:17:\"uagb\/loop-builder\";i:1;s:18:\"uagb\/loop-category\";i:0;s:20:\"uagb\/loop-pagination\";i:0;s:15:\"uagb\/loop-reset\";i:0;s:16:\"uagb\/loop-search\";i:0;s:14:\"uagb\/loop-sort\";i:0;s:17:\"uagb\/loop-wrapper\";i:1;s:13:\"uagb\/register\";i:0;s:19:\"uagb\/register-email\";i:0;s:24:\"uagb\/register-first-name\";i:0;s:23:\"uagb\/register-last-name\";i:0;s:22:\"uagb\/register-password\";i:0;s:30:\"uagb\/register-reenter-password\";i:0;s:19:\"uagb\/register-terms\";i:0;s:22:\"uagb\/register-username\";i:0;}"],"_uagb_last_spectra_edit":["1776805429"],"site-sidebar-layout":["default"],"site-content-layout":[""],"site-content-style":["default"],"site-sidebar-style":["default"],"ast-global-header-display":[""],"ast-banner-title-visibility":[""],"ast-main-header-display":[""],"ast-hfb-above-header-display":[""],"ast-hfb-below-header-display":[""],"ast-hfb-mobile-header-display":[""],"site-post-title":[""],"ast-breadcrumbs-content":[""],"ast-featured-img":[""],"footer-sml-layout":[""],"ast-disable-related-posts":[""],"header-above-stick-meta":[""],"header-main-stick-meta":[""],"header-below-stick-meta":[""],"ast-page-background-enabled":["default"],"ast-page-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-4)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"ast-content-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"enclosure":["https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/04\/continuous-calibration-web.mp4\n122826\nvideo\/mp4\n","https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/05\/primex22-color-ring-web.mp4\n570625\nvideo\/mp4\n","https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/05\/what-is-motive-web-2x.mp4\n3546645\nvideo\/mp4\n"],"_dp_original":["10000"],"_cmplz_wsc_scanned_post":["1783043034"],"_uag_css_file_name":["uag-css-10872.css"],"_uag_js_file_name":["uag-js-10872.js"],"_uag_page_assets":["a:9:{s:3:\"css\";s:349108:\".wp-block-uagb-container.uagb-block-04b07a79 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-04b07a79 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-04b07a79 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-04b07a79 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-04b07a79 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-04b07a79{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-04b07a79 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-04b07a79{box-shadow: 0px 0px   #00000070 ;padding-top: 50px;padding-bottom: 50px;padding-left: 15px;padding-right: 15px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-c874a272.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-c874a272.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-c874a272.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c874a272.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c874a272.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c874a272.wp-block-uagb-advanced-heading .uagb-separator{border-top-style: solid;border-top-width: 2px;width: 12%;border-color: var(--ast-global-color-0);margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-c874a272 .uagb-heading-text{margin-bottom: 15px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-04b07a79{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-04b07a79 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-04b07a79{padding-top: 50px;padding-bottom: 50px;padding-left: 15px;padding-right: 15px;margin-top:  !important;margin-bottom:  !important;order: initial;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-04b07a79{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-04b07a79 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-04b07a79{padding-top: 50px;padding-bottom: 50px;padding-left: 15px;padding-right: 15px;margin-top:  !important;margin-bottom:  !important;order: initial;}}.wp-block-uagb-container.uagb-block-87a8d82a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-87a8d82a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-87a8d82a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-87a8d82a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-87a8d82a .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-87a8d82a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-87a8d82a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-87a8d82a{box-shadow: 0px 0px   #00000070 ;padding-top: 50px;padding-bottom: 30px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-2);;row-gap: 20px;column-gap: 20px;}.uagb-block-1fff170c .uagb-ifb-icon{width: 25px;line-height: 25px;}.uagb-block-1fff170c .uagb-ifb-icon > span{font-size: 25px;width: 25px;line-height: 25px;color: var(--ast-global-color-5);}.uagb-block-1fff170c .uagb-ifb-icon svg{fill: var(--ast-global-color-5);}.uagb-block-1fff170c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 25px;height: 25px;line-height: 25px;font-size: 25px;color: var(--ast-global-color-5);fill: var(--ast-global-color-5);}.uagb-block-1fff170c .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 25px;font-size: 25px;color: var(--ast-global-color-5);fill: var(--ast-global-color-5);}.uagb-block-1fff170c .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 25px;height: 25px;line-height: 25px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-1fff170c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-1fff170c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-1fff170c .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 25px;line-height: 25px;font-size: 25px;color: var(--ast-global-color-5);fill: var(--ast-global-color-5);}.uagb-block-1fff170c .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 25px;line-height: 25px;font-size: 25px;color: var(--ast-global-color-5);fill: var(--ast-global-color-5);}.uagb-block-1fff170c .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-1fff170c .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-1fff170c.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-1fff170c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-1fff170c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-1fff170c.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-1fff170c .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-1fff170c .uagb-ifb-title{font-size: 1.5em;color: var(--ast-global-color-5);margin-bottom: 10px;}.uagb-block-1fff170c .uagb-ifb-desc{color: var(--ast-global-color-5);margin-bottom: 20px;}.uagb-block-1fff170c .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-1fff170c .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-1fff170c .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-1fff170c .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-1fff170c.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-1fff170c.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-1fff170c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-1fff170c .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-1fff170c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-1fff170c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-1fff170c.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-1fff170c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-1fff170c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-1fff170c.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-1fff170c.uagb-infobox-left{text-align: right;}[dir=rtl] .uagb-block-1fff170c.uagb-infobox-right{text-align: left;}[dir=rtl] .uagb-block-1fff170c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-45a1a311 .uagb-ifb-icon{width: 25px;line-height: 25px;}.uagb-block-45a1a311 .uagb-ifb-icon > span{font-size: 25px;width: 25px;line-height: 25px;color: var(--ast-global-color-5);}.uagb-block-45a1a311 .uagb-ifb-icon svg{fill: var(--ast-global-color-5);}.uagb-block-45a1a311.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 25px;height: 25px;line-height: 25px;font-size: 25px;color: var(--ast-global-color-5);fill: var(--ast-global-color-5);}.uagb-block-45a1a311 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 25px;font-size: 25px;color: var(--ast-global-color-5);fill: var(--ast-global-color-5);}.uagb-block-45a1a311 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 25px;height: 25px;line-height: 25px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-45a1a311.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-45a1a311.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-45a1a311 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 25px;line-height: 25px;font-size: 25px;color: var(--ast-global-color-5);fill: var(--ast-global-color-5);}.uagb-block-45a1a311 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 25px;line-height: 25px;font-size: 25px;color: var(--ast-global-color-5);fill: var(--ast-global-color-5);}.uagb-block-45a1a311 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-45a1a311 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-45a1a311.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-45a1a311.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-45a1a311.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-45a1a311.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-45a1a311 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-45a1a311 .uagb-ifb-title{font-size: 1.5em;color: var(--ast-global-color-5);margin-bottom: 10px;}.uagb-block-45a1a311 .uagb-ifb-desc{color: var(--ast-global-color-5);margin-bottom: 20px;}.uagb-block-45a1a311 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-45a1a311 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-45a1a311 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-45a1a311 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-45a1a311.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-45a1a311.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-45a1a311.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-45a1a311 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-45a1a311.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-45a1a311.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-45a1a311.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-45a1a311.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-45a1a311.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-45a1a311.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-45a1a311.uagb-infobox-left{text-align: right;}[dir=rtl] .uagb-block-45a1a311.uagb-infobox-right{text-align: left;}[dir=rtl] .uagb-block-45a1a311.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-19a3586d .uagb-ifb-icon{width: 25px;line-height: 25px;}.uagb-block-19a3586d .uagb-ifb-icon > span{font-size: 25px;width: 25px;line-height: 25px;color: var(--ast-global-color-5);}.uagb-block-19a3586d .uagb-ifb-icon svg{fill: var(--ast-global-color-5);}.uagb-block-19a3586d.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 25px;height: 25px;line-height: 25px;font-size: 25px;color: var(--ast-global-color-5);fill: var(--ast-global-color-5);}.uagb-block-19a3586d .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 25px;font-size: 25px;color: var(--ast-global-color-5);fill: var(--ast-global-color-5);}.uagb-block-19a3586d .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 25px;height: 25px;line-height: 25px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-19a3586d.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-19a3586d.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-19a3586d .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 25px;line-height: 25px;font-size: 25px;color: var(--ast-global-color-5);fill: var(--ast-global-color-5);}.uagb-block-19a3586d .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 25px;line-height: 25px;font-size: 25px;color: var(--ast-global-color-5);fill: var(--ast-global-color-5);}.uagb-block-19a3586d .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-19a3586d .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-19a3586d.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-19a3586d.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-19a3586d.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-19a3586d.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-19a3586d .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-19a3586d .uagb-ifb-title{font-size: 1.5em;color: var(--ast-global-color-5);margin-bottom: 10px;}.uagb-block-19a3586d .uagb-ifb-desc{color: var(--ast-global-color-5);margin-bottom: 20px;}.uagb-block-19a3586d .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-19a3586d .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-19a3586d .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-19a3586d .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-19a3586d.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-19a3586d.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-19a3586d.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-19a3586d .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-19a3586d.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-19a3586d.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-19a3586d.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-19a3586d.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-19a3586d.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-19a3586d.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-19a3586d.uagb-infobox-left{text-align: right;}[dir=rtl] .uagb-block-19a3586d.uagb-infobox-right{text-align: left;}[dir=rtl] .uagb-block-19a3586d.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-87a8d82a{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-87a8d82a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-87a8d82a{padding-top: 50px;padding-bottom: 30px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-2);;}.uagb-block-1fff170c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 25px;height: 25px;line-height: 25px;font-size: 25px;}.uagb-block-1fff170c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 25px;font-size: 25px;}.uagb-block-1fff170c.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-1fff170c .uagb-ifb-icon{width: 25px;line-height: 25px;}.uagb-block-1fff170c .uagb-ifb-icon > span{font-size: 25px;width: 25px;line-height: 25px;}.uagb-block-1fff170c .uagb-iconbox-icon-wrap{width: 25px;height: 25px;line-height: 25px;}.uagb-block-1fff170c .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 25px;line-height: 25px;font-size: 25px;}.uagb-block-1fff170c .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 25px;line-height: 25px;font-size: 25px;}.uagb-block-1fff170c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-1fff170c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-45a1a311.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 25px;height: 25px;line-height: 25px;font-size: 25px;}.uagb-block-45a1a311.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 25px;font-size: 25px;}.uagb-block-45a1a311.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-45a1a311 .uagb-ifb-icon{width: 25px;line-height: 25px;}.uagb-block-45a1a311 .uagb-ifb-icon > span{font-size: 25px;width: 25px;line-height: 25px;}.uagb-block-45a1a311 .uagb-iconbox-icon-wrap{width: 25px;height: 25px;line-height: 25px;}.uagb-block-45a1a311 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 25px;line-height: 25px;font-size: 25px;}.uagb-block-45a1a311 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 25px;line-height: 25px;font-size: 25px;}.uagb-block-45a1a311.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-45a1a311.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-19a3586d.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 25px;height: 25px;line-height: 25px;font-size: 25px;}.uagb-block-19a3586d.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 25px;font-size: 25px;}.uagb-block-19a3586d.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-19a3586d .uagb-ifb-icon{width: 25px;line-height: 25px;}.uagb-block-19a3586d .uagb-ifb-icon > span{font-size: 25px;width: 25px;line-height: 25px;}.uagb-block-19a3586d .uagb-iconbox-icon-wrap{width: 25px;height: 25px;line-height: 25px;}.uagb-block-19a3586d .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 25px;line-height: 25px;font-size: 25px;}.uagb-block-19a3586d .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 25px;line-height: 25px;font-size: 25px;}.uagb-block-19a3586d.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-19a3586d.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-87a8d82a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-87a8d82a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-87a8d82a{padding-top: 50px;padding-bottom: 30px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-2);;}.uagb-block-1fff170c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 25px;height: 25px;line-height: 25px;font-size: 25px;}.uagb-block-1fff170c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 25px;font-size: 25px;}.uagb-block-1fff170c .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 25px;line-height: 25px;font-size: 25px;}.uagb-block-1fff170c .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 25px;line-height: 25px;font-size: 25px;}.uagb-block-1fff170c.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-1fff170c .uagb-ifb-icon{width: 25px;line-height: 25px;}.uagb-block-1fff170c .uagb-ifb-icon > span{font-size: 25px;width: 25px;line-height: 25px;}.uagb-block-1fff170c .uagb-iconbox-icon-wrap{width: 25px;height: 25px;line-height: 25px;}.uagb-block-1fff170c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-1fff170c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-45a1a311.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 25px;height: 25px;line-height: 25px;font-size: 25px;}.uagb-block-45a1a311.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 25px;font-size: 25px;}.uagb-block-45a1a311 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 25px;line-height: 25px;font-size: 25px;}.uagb-block-45a1a311 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 25px;line-height: 25px;font-size: 25px;}.uagb-block-45a1a311.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-45a1a311 .uagb-ifb-icon{width: 25px;line-height: 25px;}.uagb-block-45a1a311 .uagb-ifb-icon > span{font-size: 25px;width: 25px;line-height: 25px;}.uagb-block-45a1a311 .uagb-iconbox-icon-wrap{width: 25px;height: 25px;line-height: 25px;}.uagb-block-45a1a311.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-45a1a311.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-19a3586d.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 25px;height: 25px;line-height: 25px;font-size: 25px;}.uagb-block-19a3586d.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 25px;font-size: 25px;}.uagb-block-19a3586d .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 25px;line-height: 25px;font-size: 25px;}.uagb-block-19a3586d .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 25px;line-height: 25px;font-size: 25px;}.uagb-block-19a3586d.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-19a3586d .uagb-ifb-icon{width: 25px;line-height: 25px;}.uagb-block-19a3586d .uagb-ifb-icon > span{font-size: 25px;width: 25px;line-height: 25px;}.uagb-block-19a3586d .uagb-iconbox-icon-wrap{width: 25px;height: 25px;line-height: 25px;}.uagb-block-19a3586d.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-19a3586d.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}.wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all .3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}.uagb-buttons__outer-wrap .uagb-buttons__wrap{display:inline-flex;width:100%}.uagb-buttons__outer-wrap.uagb-btn__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}@media(max-width: 976px){.uagb-buttons__outer-wrap.uagb-btn-tablet__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn-tablet__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn-tablet__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn-tablet__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}}@media(max-width: 767px){.uagb-buttons__outer-wrap.uagb-btn-mobile__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn-mobile__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn-mobile__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn-mobile__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}}.uagb-buttons__outer-wrap .uagb-buttons-repeater{display:flex;justify-content:center;align-items:center;transition:box-shadow .2s ease}.uagb-buttons__outer-wrap .uagb-buttons-repeater a.uagb-button__link{display:flex;justify-content:center}.uagb-buttons__outer-wrap .uagb-buttons-repeater .uagb-button__icon{font-size:inherit;display:flex;align-items:center}.uagb-buttons__outer-wrap .uagb-buttons-repeater .uagb-button__icon svg{fill:currentColor;width:inherit;height:inherit}.uagb-ifb-content>svg *{-webkit-transition:all .2s;-o-transition:all .2s;transition:all .2s}.uagb-ifb-content>svg,.uagb-ifb-content{display:inline-block}.uagb-ifb-content>svg{vertical-align:middle;width:inherit;height:inherit;font-style:initial}.uagb-ifb-content .uagb-ifb-icon-wrap svg{box-sizing:content-box;width:inherit;height:inherit}.uagb-ifb-button-wrapper:empty{display:none}div.uagb-ifb-button-wrapper a.uagb-infobox-cta-link,div.uagb-ifb-cta a.uagb-infobox-cta-link,.entry .entry-content a.uagb-infobox-cta-link,a.uagb-infobox-link-wrap,.entry .entry-content a.uagb-infobox-link-wrap{text-decoration:none;align-items:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-middle .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-middle .uagb-ifb-content{-ms-flex-item-align:center;-webkit-align-self:center;align-self:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-image-valign-top .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-top .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-top .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-top .uagb-ifb-content{-webkit-align-self:self-start;align-self:self-start}.uagb-infobox-left{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-center{justify-content:center;text-align:center;-webkit-box-pack:center;-ms-flex-pack:center;-webkit-justify-content:center;-moz-box-pack:center}.uagb-infobox-right{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}.uagb-infobox-icon-above-title.uagb-infobox__content-wrap,.uagb-infobox-icon-below-title.uagb-infobox__content-wrap{display:block;width:100%}.uagb-infobox-icon-left-title .uagb-ifb-content>svg,.uagb-infobox-icon-left .uagb-ifb-content>svg{margin-right:10px}.uagb-infobox-icon-right-title .uagb-ifb-content>svg,.uagb-infobox-icon-right .uagb-ifb-content>svg{margin-left:10px}.uagb-infobox-icon-left.uagb-infobox__content-wrap,.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:-webkit-flex;display:-moz-box;display:flex;-js-display:flex}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-image-content,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-image-content,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{flex-shrink:0;line-height:0}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-left .uagb-ifb-content,.uagb-infobox-icon-right .uagb-ifb-content{flex-grow:1}.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}.uagb-ifb-content img{position:relative;display:inline-block;line-height:0;width:auto;height:auto !important;max-width:100%;border-radius:inherit;-webkit-box-sizing:content-box;-moz-box-sizing:content-box;-webkit-border-radius:inherit}.uagb-infobox-module-link{position:absolute;top:0;right:0;bottom:0;left:0;z-index:4;width:100%;height:100%}.uagb-edit-mode .uagb-infobox-module-link{z-index:2}.uagb-infobox-link-icon-after{margin-right:0;margin-left:5px}.uagb-infobox-link-icon-before{margin-right:5px;margin-left:0}.uagb-infobox-link-icon{-webkit-transition:all 200ms linear;transition:all 200ms linear}.uagb-infobox__content-wrap{box-sizing:border-box;position:relative;width:100%;word-break:break-word;z-index:1}.uagb-ifb-separator{display:inline-block;margin:0;border-top-color:#333;border-top-style:solid;border-top-width:2px;line-height:0}.uagb-ifb-button-wrapper{line-height:1}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link{background-color:unset;border:none}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link:hover{background-color:unset;border-color:unset}.uagb-ifb-button-wrapper .uagb-infobox-cta-link{cursor:pointer}.uagb-ifb-button-wrapper .uagb-infobox-cta-link.wp-block-button__link{width:auto}.uagb-ifb-button-wrapper .wp-block-button__link svg,.uagb-ifb-button-wrapper .ast-outline-button svg{fill:currentColor}.uagb-infobox__content-wrap a{-webkit-box-shadow:none;box-shadow:none;text-decoration:none}.uagb-ifb-title-wrap{width:100%}.uagb-ifb-title{margin-block-start:0}.uagb-ifb-title-wrap .uagb-ifb-title-prefix{display:block;padding:0;margin:0}.uagb-infobox__content-wrap.uagb-infobox__content-wrap{position:relative}.uagb-ifb-content{width:100%}.uagb-infobox__content-wrap.uagb-infobox,.uagb-ifb-content,.uagb-ifb-title-wrap,.uagb-ifb-title-prefix *,svg.dashicon.dashicons-upload{z-index:1}a.uagb-infobox-link-wrap{color:inherit}.uagb-ifb-content p:empty{display:none}.uagb-infobox__content-wrap .uagb-ifb-content img{display:inline-block;max-width:100%}.uagb-infobox__content-wrap .uagb-ifb-content svg{display:inline-block}.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{box-sizing:content-box}.uagb-infobox-cta-link>svg{vertical-align:middle;width:15px;height:15px;font-size:15px}.uagb-infobox-cta-link{display:inline-flex}.block-editor-page #wpwrap .uagb-infobox-cta-link svg,.uagb-infobox-cta-link svg{font-style:normal}.uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}.uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}html[dir=rtl] .uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,html[dir=rtl] .uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}html[dir=rtl] .uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,html[dir=rtl] .uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}html[dir=rtl] .uagb-infobox-left{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}html[dir=rtl] .uagb-infobox-right{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-icon-left .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:flex}.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}a.uagb-infbox__link-to-all{position:absolute;top:0;left:0;z-index:3;width:100%;height:100%;box-shadow:none;text-decoration:none;-webkit-box-shadow:none}@media only screen and (max-width: 976px){.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{padding:0;margin-bottom:20px}.uagb-infobox-stacked-tablet.uagb-reverse-order-tablet.uagb-infobox__content-wrap{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-content,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{display:block;width:100%;text-align:center}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{margin-right:0;margin-left:0}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}@media screen and (max-width: 767px){.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap{padding:0;margin-bottom:20px;margin-right:0;margin-left:0}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap.uagb-reverse-order-mobile{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-content{display:block;width:100%;text-align:center}.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}.uagb-ifb-icon svg{width:inherit;height:inherit;vertical-align:middle}.uagb-ifb-button-icon{height:15px;width:15px;font-size:15px;vertical-align:middle}.uagb-ifb-button-icon svg{height:inherit;width:inherit;display:inline-block}.uagb-ifb-button-icon.uagb-ifb-align-icon-after{float:right}.uagb-ifb-cta-button{display:inline-block}.uagb-disable-link{pointer-events:none}@media only screen and (min-width: 977px){.uagb-infobox-margin-wrapper{display:flex}}.uagb-ifb-content .uagb-ifb-desc p:last-child{margin-bottom:0}html[dir=rtl] .uagb-infobox-icon-left-title .uagb-ifb-content>svg,html[dir=rtl] .uagb-infobox-icon-left .uagb-ifb-content>svg{margin-right:0;margin-left:10px}html[dir=rtl] .uagb-infobox-icon-right-title .uagb-ifb-content>svg,html[dir=rtl] .uagb-infobox-icon-right .uagb-ifb-content>svg{margin-left:0;margin-right:10px}html[dir=rtl] .uagb-infobox-link-icon-after{margin-right:5px;margin-left:0}html[dir=rtl] .uagb-infobox-link-icon-before{margin-right:0;margin-left:5px}html[dir=rtl] .uagb-ifb-button-icon.uagb-ifb-align-icon-after{float:left}.wp-block-uagb-faq{width:100%}.wp-block-uagb-faq.uagb-faq-layout-accordion .uagb-faq-child__outer-wrap .uagb-faq-questions-button{cursor:pointer}.wp-block-uagb-faq .uagb-faq-content{margin-bottom:0}.wp-block-uagb-faq .uagb-faq-content p{margin:auto}.uagb-faq-layout-grid.uagb-faq-equal-height.uagb-faq__wrap .uagb-faq-child__outer-wrap,.uagb-faq-layout-grid.uagb-faq-equal-height.uagb-faq__wrap .uagb-faq-item{height:100%}body[class*=astra] .uagb-faq-questions{line-height:normal}.uagb-faq-item{overflow:hidden}.wp-block-uagb-faq-child .uagb-faq-questions-button{display:flex;align-items:center}.wp-block-uagb-faq-child .uagb-faq-questions-button .uagb-faq-icon-wrap{display:flex;align-items:center}.wp-block-uagb-faq-child .uagb-faq-questions-button .uagb-question{width:100%;margin-top:0;margin-bottom:0}.wp-block-uagb-faq-child .uagb-icon svg,.wp-block-uagb-faq-child .uagb-icon-active svg{width:15px;height:15px;font-size:15px}.wp-block-uagb-faq-child.uagb-faq-child__outer-wrap.uagb-faq-item .uagb-icon-active,.wp-block-uagb-faq-child.uagb-faq-child__outer-wrap.uagb-faq-item.uagb-faq-item-active .uagb-icon,.wp-block-uagb-faq-child.uagb-faq-child__outer-wrap .uagb-faq-item .uagb-icon-active,.wp-block-uagb-faq-child.uagb-faq-child__outer-wrap .uagb-faq-item.uagb-faq-item-active .uagb-icon{display:none;width:0;height:0;margin:0}.wp-block-uagb-faq-child.uagb-faq-child__outer-wrap.uagb-faq-item .uagb-icon,.wp-block-uagb-faq-child.uagb-faq-child__outer-wrap.uagb-faq-item.uagb-faq-item-active .uagb-icon-active,.wp-block-uagb-faq-child.uagb-faq-child__outer-wrap .uagb-faq-item .uagb-icon,.wp-block-uagb-faq-child.uagb-faq-child__outer-wrap .uagb-faq-item.uagb-faq-item-active .uagb-icon-active{display:flex;width:auto;height:auto}.uagb-faq-layout-grid .uagb-faq-child__outer-wrap.uagb-faq-item .uagb-icon,.uagb-faq-layout-grid .uagb-faq-child__outer-wrap.uagb-faq-item.uagb-faq-item-active .uagb-icon-active,.uagb-faq-layout-grid .uagb-faq-child__outer-wrap .uagb-faq-item .uagb-icon,.uagb-faq-layout-grid .uagb-faq-child__outer-wrap .uagb-faq-item.uagb-faq-item-active .uagb-icon-active{display:none}.uagb-faq-layout-grid .uagb-faq-child__outer-wrap.uagb-faq-item span.uagb-icon-active.uagb-faq-icon-wrap,.uagb-faq-layout-grid .uagb-faq-child__outer-wrap.uagb-faq-item.uagb-faq-item-active .uagb-icon-active,.uagb-faq-layout-grid .uagb-faq-child__outer-wrap .uagb-faq-item span.uagb-icon-active.uagb-faq-icon-wrap,.uagb-faq-layout-grid .uagb-faq-child__outer-wrap .uagb-faq-item.uagb-faq-item-active .uagb-icon-active{display:none}.wp-block-uagb-image{display:flex}.wp-block-uagb-image__figure{position:relative;display:flex;flex-direction:column;max-width:100%;height:auto;margin:0}.wp-block-uagb-image__figure img{height:auto;display:flex;max-width:100%;transition:box-shadow .2s ease}.wp-block-uagb-image__figure>a{display:inline-block}.wp-block-uagb-image__figure figcaption{text-align:center;margin-top:.5em;margin-bottom:1em}.wp-block-uagb-image .components-placeholder.block-editor-media-placeholder .components-placeholder__instructions{align-self:center}.wp-block-uagb-image--align-left{text-align:left}.wp-block-uagb-image--align-right{text-align:right}.wp-block-uagb-image--align-center{text-align:center}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw);max-width:100vw;width:100vw;height:auto}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure img{height:auto;width:100% !important}.wp-block-uagb-image--align-wide .wp-block-uagb-image__figure img{height:auto;width:100%}.wp-block-uagb-image--layout-overlay__color-wrapper{position:absolute;left:0;top:0;right:0;bottom:0;opacity:.2;background:rgba(0,0,0,.5);transition:opacity .35s ease-in-out}.wp-block-uagb-image--layout-overlay-link{position:absolute;left:0;right:0;bottom:0;top:0}.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity:1}.wp-block-uagb-image--layout-overlay__inner{position:absolute;left:15px;right:15px;bottom:15px;top:15px;display:flex;align-items:center;justify-content:center;flex-direction:column;border-color:#fff;transition:.35s ease-in-out}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.top-center,.wp-block-uagb-image--layout-overlay__inner.top-right{justify-content:flex-start}.wp-block-uagb-image--layout-overlay__inner.bottom-left,.wp-block-uagb-image--layout-overlay__inner.bottom-center,.wp-block-uagb-image--layout-overlay__inner.bottom-right{justify-content:flex-end}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.center-left,.wp-block-uagb-image--layout-overlay__inner.bottom-left{align-items:flex-start}.wp-block-uagb-image--layout-overlay__inner.top-right,.wp-block-uagb-image--layout-overlay__inner.center-right,.wp-block-uagb-image--layout-overlay__inner.bottom-right{align-items:flex-end}.wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{color:#fff;transition:transform .35s,opacity .35s ease-in-out;transform:translate3d(0, 24px, 0);margin:0;line-height:1em}.wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width:30%;border-top-width:2px;border-top-color:#fff;border-top-style:solid;margin-bottom:10px;opacity:0;transition:transform .4s,opacity .4s ease-in-out;transform:translate3d(0, 30px, 0)}.wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity:0;overflow:visible;color:#fff;transition:transform .45s,opacity .45s ease-in-out;transform:translate3d(0, 35px, 0)}.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-heading,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-separator,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-caption{opacity:1;transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1.05)}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{width:calc(100% + 40px) !important;max-width:none !important;transform:translate3d(-40px, 0, 0);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-grayscale img{filter:grayscale(0%);transition:.35s ease-in-out}.wp-block-uagb-image--effect-grayscale:hover img{filter:grayscale(100%)}.wp-block-uagb-image--effect-blur img{filter:blur(0);transition:.35s ease-in-out}.wp-block-uagb-image--effect-blur:hover img{filter:blur(3px)}.wp-block-uagb-container.uagb-block-c37632dd .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c37632dd .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c37632dd .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c37632dd .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c37632dd .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c37632dd{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c37632dd > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-c37632dd{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-4);;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-8160c408 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-8160c408 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-8160c408 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-8160c408 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-8160c408 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8160c408{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8160c408 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-8160c408{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-b39dc514.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-b39dc514.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-b39dc514.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-b39dc514.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-57b573d8 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-57b573d8 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-57b573d8 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-57b573d8 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-57b573d8 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-57b573d8{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-57b573d8 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-57b573d8{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-efb600c6.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-efb600c6.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.wp-block-uagb-buttons .uagb-block-6c86d97c .wp-block-button__link{background: transparent;}.wp-block-uagb-buttons .uagb-block-6c86d97c .uagb-button__wrapper .uagb-buttons-repeater{color: var(--ast-global-color-2);}.wp-block-uagb-buttons .uagb-block-6c86d97c .wp-block-button__link.has-text-color:hover .uagb-button__link{color: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-6c86d97c .wp-block-button__link.has-text-color:focus .uagb-button__link{color: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-6c86d97c .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-6c86d97c .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-6c86d97c .uagb-buttons-repeater.wp-block-button__link{border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: #333;border-style: none;}.wp-block-uagb-buttons .uagb-block-6c86d97c .uagb-buttons-repeater.wp-block-button__link:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-6c86d97c .uagb-buttons-repeater.wp-block-button__link:focus{border-color: #333;}.wp-block-uagb-buttons .uagb-block-6c86d97c.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: #333;border-style: none;}.wp-block-uagb-buttons .uagb-block-6c86d97c.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-6c86d97c .uagb-buttons-repeater .uagb-button__link{color: var(--ast-global-color-2);}.wp-block-uagb-buttons .uagb-block-6c86d97c .uagb-buttons-repeater:hover .uagb-button__link{color: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-6c86d97c .uagb-buttons-repeater:focus .uagb-button__link{color: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-6c86d97c .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: var(--ast-global-color-2);}.wp-block-uagb-buttons .uagb-block-6c86d97c .uagb-buttons-repeater:hover .uagb-button__icon > svg{fill: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-6c86d97c .uagb-buttons-repeater:focus .uagb-button__icon > svg{fill: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-6c86d97c .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 12px;}.wp-block-uagb-buttons .uagb-block-6c86d97c .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 12px;}.wp-block-uagb-buttons .uagb-block-6c86d97c .uagb-button__link{text-transform: normal;text-decoration: none;}.wp-block-uagb-buttons .uagb-block-8368e105 .wp-block-button__link{background: transparent;}.wp-block-uagb-buttons .uagb-block-8368e105 .wp-block-button__link:hover{background: ;;background-clip: padding-box;}.wp-block-uagb-buttons .uagb-block-8368e105 .wp-block-button__link:focus{background: ;;background-clip: padding-box;}.wp-block-uagb-buttons .uagb-block-8368e105 .uagb-button__wrapper .uagb-buttons-repeater{color: var(--ast-global-color-2);}.wp-block-uagb-buttons .uagb-block-8368e105 .wp-block-button__link.has-text-color:hover .uagb-button__link{color: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-8368e105 .wp-block-button__link.has-text-color:focus .uagb-button__link{color: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-8368e105 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-8368e105 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-8368e105 .uagb-buttons-repeater.wp-block-button__link{border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: #333;border-style: none;}.wp-block-uagb-buttons .uagb-block-8368e105 .uagb-buttons-repeater.wp-block-button__link:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-8368e105 .uagb-buttons-repeater.wp-block-button__link:focus{border-color: #333;}.wp-block-uagb-buttons .uagb-block-8368e105.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: #333;border-style: none;}.wp-block-uagb-buttons .uagb-block-8368e105.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-8368e105 .uagb-buttons-repeater .uagb-button__link{color: var(--ast-global-color-2);}.wp-block-uagb-buttons .uagb-block-8368e105 .uagb-buttons-repeater:hover .uagb-button__link{color: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-8368e105 .uagb-buttons-repeater:focus .uagb-button__link{color: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-8368e105 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: var(--ast-global-color-2);}.wp-block-uagb-buttons .uagb-block-8368e105 .uagb-buttons-repeater:hover .uagb-button__icon > svg{fill: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-8368e105 .uagb-buttons-repeater:focus .uagb-button__icon > svg{fill: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-8368e105 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 12px;}.wp-block-uagb-buttons .uagb-block-8368e105 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 12px;}.wp-block-uagb-buttons .uagb-block-8368e105 .uagb-button__link{text-transform: normal;text-decoration: none;}.wp-block-uagb-container.uagb-block-217fd5a5 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-217fd5a5 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-217fd5a5 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-217fd5a5 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-217fd5a5 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-217fd5a5{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-217fd5a5{min-height: 500px;box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 50% 50%;background-size: cover;background-attachment: scroll;background-image: url(https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/04\/primex22-hero-desktop-v2-2000x600-1.jpg);background-clip: padding-box;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-49ad00df .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-49ad00df .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-49ad00df .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-49ad00df .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-49ad00df .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-49ad00df{max-width: 75%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-49ad00df > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-49ad00df.uagb-layout-grid{row-gap: 0px;column-gap: 0px;grid-template-columns: minmax( 1px, 1fr)  minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: center;justify-items: start;align-content: center;justify-content: stretch;}.wp-block-uagb-container.uagb-block-49ad00df{min-height: 300px;box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;}.wp-block-uagb-advanced-heading.uagb-block-2a25eb4d.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-5);}.wp-block-uagb-advanced-heading.uagb-block-2a25eb4d.wp-block-uagb-advanced-heading {text-align: center;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-2a25eb4d.wp-block-uagb-advanced-heading .uagb-desc-text{color: var(--ast-global-color-5);margin-bottom: 79px;}.wp-block-uagb-advanced-heading.uagb-block-2a25eb4d.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-2a25eb4d.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-2a25eb4d.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-2a25eb4d.wp-block-uagb-advanced-heading .uagb-separator{border-top-style: solid;border-top-width: 2px;width: 12%;border-color: var(--ast-global-color-0);margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-2a25eb4d .uagb-heading-text{margin-bottom: 15px;}.wp-block-uagb-container.uagb-block-01a5ec31 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-01a5ec31 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-01a5ec31 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-01a5ec31 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-01a5ec31 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-01a5ec31{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-01a5ec31 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-01a5ec31{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-98b90e67 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-98b90e67 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-98b90e67 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-98b90e67 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-98b90e67 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-98b90e67{max-width: 25%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-98b90e67 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-98b90e67{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-24eed835 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-24eed835 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-24eed835 .uagb-ifb-icon svg{fill: #333;}.uagb-block-24eed835.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-24eed835 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-24eed835 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-24eed835.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-24eed835.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-24eed835 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-24eed835 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-24eed835 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-24eed835 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-24eed835.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-24eed835.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-24eed835.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-24eed835.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-24eed835 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-24eed835 .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-24eed835 .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-24eed835 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-24eed835 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-24eed835 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-24eed835 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-24eed835.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-24eed835.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-24eed835 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-24eed835.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-24eed835.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-24eed835.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-24eed835.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-24eed835 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-24eed835.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-24eed835.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-24eed835.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-24eed835.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-24eed835.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-24eed835.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-24eed835.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-24eed835.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-24eed835.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-58da930d .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-58da930d .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-58da930d .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-58da930d .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-58da930d .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-58da930d{max-width: 25%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-58da930d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-58da930d{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-f79d1186 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-f79d1186 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-f79d1186 .uagb-ifb-icon svg{fill: #333;}.uagb-block-f79d1186.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-f79d1186 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-f79d1186 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-f79d1186.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-f79d1186.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-f79d1186 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-f79d1186 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-f79d1186 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-f79d1186 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-f79d1186.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-f79d1186.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-f79d1186.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-f79d1186.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-f79d1186 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-f79d1186 .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-f79d1186 .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-f79d1186 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-f79d1186 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-f79d1186 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-f79d1186 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-f79d1186.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-f79d1186.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-f79d1186 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-f79d1186.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-f79d1186.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-f79d1186.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-f79d1186.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-f79d1186 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-f79d1186.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-f79d1186.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-f79d1186.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-f79d1186.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-f79d1186.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-f79d1186.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-f79d1186.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-f79d1186.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-f79d1186.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-39ee6f6a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-39ee6f6a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-39ee6f6a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-39ee6f6a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-39ee6f6a .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-39ee6f6a{max-width: 25%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-39ee6f6a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-39ee6f6a{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-4ab4d9d6 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-4ab4d9d6 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-4ab4d9d6 .uagb-ifb-icon svg{fill: #333;}.uagb-block-4ab4d9d6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-4ab4d9d6 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-4ab4d9d6 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-4ab4d9d6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-4ab4d9d6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-4ab4d9d6 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-4ab4d9d6 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-4ab4d9d6 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-4ab4d9d6 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-4ab4d9d6.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-4ab4d9d6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-4ab4d9d6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-4ab4d9d6.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-4ab4d9d6 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-4ab4d9d6 .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-4ab4d9d6 .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-4ab4d9d6 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-4ab4d9d6 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-4ab4d9d6 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-4ab4d9d6 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-4ab4d9d6.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-4ab4d9d6.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-4ab4d9d6 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-4ab4d9d6.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-4ab4d9d6.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-4ab4d9d6.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-4ab4d9d6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-4ab4d9d6 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4ab4d9d6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4ab4d9d6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4ab4d9d6.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4ab4d9d6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4ab4d9d6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4ab4d9d6.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4ab4d9d6.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-4ab4d9d6.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-4ab4d9d6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-a2f6c5e0 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a2f6c5e0 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a2f6c5e0 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a2f6c5e0 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a2f6c5e0 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a2f6c5e0{max-width: 25%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a2f6c5e0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-a2f6c5e0{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-32bcbeda .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-32bcbeda .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-32bcbeda .uagb-ifb-icon svg{fill: #333;}.uagb-block-32bcbeda.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-32bcbeda .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-32bcbeda .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-32bcbeda.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-32bcbeda.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-32bcbeda .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-32bcbeda .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-32bcbeda .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-32bcbeda .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-32bcbeda.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-32bcbeda.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-32bcbeda.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-32bcbeda.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-32bcbeda .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-32bcbeda .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-32bcbeda .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-32bcbeda .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-32bcbeda .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-32bcbeda .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-32bcbeda .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-32bcbeda.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-32bcbeda.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-32bcbeda .uagb-infobox__content-wrap{text-align: center;}.uagb-block-32bcbeda.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-32bcbeda.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-32bcbeda.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-32bcbeda.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-32bcbeda .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-32bcbeda.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-32bcbeda.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-32bcbeda.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-32bcbeda.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-32bcbeda.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-32bcbeda.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-32bcbeda.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-32bcbeda.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-32bcbeda.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-80b095e0 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-80b095e0 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-80b095e0 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-80b095e0 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-80b095e0 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-80b095e0{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-80b095e0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-80b095e0.uagb-layout-grid > .uagb-container-inner-blocks-wrap{row-gap: 20px;column-gap: 20px;grid-template-columns: minmax( 1px, 1fr)  minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-80b095e0{min-height: 400px;box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;}.wp-block-uagb-container.uagb-block-5b5f2cd6 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5b5f2cd6 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5b5f2cd6 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5b5f2cd6 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5b5f2cd6 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5b5f2cd6{max-width: 66px;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5b5f2cd6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-5b5f2cd6{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-341a0dd6.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-341a0dd6.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-341a0dd6.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-341a0dd6.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-0b1e3dc1 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-0b1e3dc1 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-0b1e3dc1 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-0b1e3dc1 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-0b1e3dc1 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0b1e3dc1{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0b1e3dc1 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-0b1e3dc1{min-height: 300px;box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 50% 50%;background-size: contain;background-attachment: scroll;background-image: url(https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/05\/marys-peak-square-2049-2000x2000-1.png);background-clip: padding-box;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-863cfced .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-863cfced .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-863cfced .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-863cfced .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-863cfced .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-863cfced{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-863cfced > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-863cfced.uagb-layout-grid > .uagb-container-inner-blocks-wrap{row-gap: 20px;column-gap: 20px;grid-template-columns: minmax( 1px, 1fr)  minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-863cfced{min-height: 400px;box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;}.wp-block-uagb-container.uagb-block-c7d62716 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c7d62716 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c7d62716 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c7d62716 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c7d62716 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c7d62716{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c7d62716 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-c7d62716{min-height: 300px;box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 50% 50%;background-size: contain;background-attachment: scroll;background-image: url(https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/05\/prime22-elegant-design.webp);background-clip: padding-box;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-e7f3e310 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e7f3e310 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e7f3e310 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e7f3e310 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e7f3e310 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e7f3e310{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e7f3e310 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-e7f3e310{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-d402941c.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-d402941c.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-d402941c.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-d402941c.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-ce0a037a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ce0a037a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ce0a037a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ce0a037a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ce0a037a .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ce0a037a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ce0a037a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-ce0a037a.uagb-layout-grid > .uagb-container-inner-blocks-wrap{row-gap: 20px;column-gap: 20px;grid-template-columns: minmax( 1px, 1fr)  minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-ce0a037a{min-height: 400px;box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;}.wp-block-uagb-container.uagb-block-3ae92481 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3ae92481 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3ae92481 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3ae92481 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3ae92481 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3ae92481{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3ae92481 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-3ae92481{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-260b1d97.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-260b1d97.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-260b1d97.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-260b1d97.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-9f65af31 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9f65af31 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9f65af31 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9f65af31 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9f65af31 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9f65af31{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9f65af31 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-9f65af31 .uagb-container__video-wrap{border-color: inherit;}.wp-block-uagb-container.uagb-block-9f65af31 > div:not(.uagb-container__video-wrap):not(.uagb-container__shape){position: relative;}.wp-block-uagb-container.wp-block-uagb-container.uagb-block-9f65af31{flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-9f65af31{min-height: 300px;box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;row-gap: 20px;column-gap: 20px;overflow: visible;}.wp-block-uagb-container.uagb-block-eb5bd218 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-eb5bd218 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-eb5bd218 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-eb5bd218 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-eb5bd218 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-eb5bd218{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-eb5bd218 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-eb5bd218.uagb-layout-grid > .uagb-container-inner-blocks-wrap{row-gap: 20px;column-gap: 20px;grid-template-columns: minmax( 1px, 1fr)  minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-eb5bd218{min-height: 400px;box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;}.wp-block-uagb-container.uagb-block-42748acf .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-42748acf .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-42748acf .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-42748acf .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-42748acf .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-42748acf{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-42748acf > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-42748acf{min-height: 300px;box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 50% 50%;background-size: contain;background-attachment: scroll;background-image: url(https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/05\/prime22-fast-glass-2x.webp);background-clip: padding-box;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-a5cf6412 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a5cf6412 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a5cf6412 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a5cf6412 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a5cf6412 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a5cf6412{max-width: 66px;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a5cf6412 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-a5cf6412{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-f2e2013f.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-f2e2013f.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f2e2013f.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f2e2013f.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-ba971622 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ba971622 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ba971622 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ba971622 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ba971622 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ba971622{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ba971622 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-ba971622.uagb-layout-grid > .uagb-container-inner-blocks-wrap{row-gap: 20px;column-gap: 20px;grid-template-columns: minmax( 1px, 1fr)  minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-ba971622{min-height: 400px;box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;}.wp-block-uagb-container.uagb-block-eef5b719 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-eef5b719 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-eef5b719 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-eef5b719 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-eef5b719 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-eef5b719{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-eef5b719 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-eef5b719{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-3cf69d08.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-3cf69d08.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-3cf69d08.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-3cf69d08.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-5074e906 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5074e906 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5074e906 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5074e906 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5074e906 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5074e906{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5074e906 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-5074e906{min-height: 300px;box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 50% 50%;background-size: contain;background-attachment: scroll;background-image: url(https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/05\/prime22-wide-angle-2x-800x600-1.webp);background-clip: padding-box;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-4a753c21 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4a753c21 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4a753c21 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4a753c21 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4a753c21 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4a753c21{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4a753c21 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-4a753c21.uagb-layout-grid > .uagb-container-inner-blocks-wrap{row-gap: 20px;column-gap: 20px;grid-template-columns: minmax( 1px, 1fr)  minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-4a753c21{min-height: 400px;box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;}.wp-block-uagb-container.uagb-block-4d6e79c8 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4d6e79c8 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4d6e79c8 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4d6e79c8 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4d6e79c8 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4d6e79c8{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4d6e79c8 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-4d6e79c8{min-height: 300px;box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 50% 50%;background-size: contain;background-attachment: scroll;background-image: url(https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/04\/on-board-processing-2x-800x487-1.webp);background-clip: padding-box;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-851a34f4 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-851a34f4 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-851a34f4 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-851a34f4 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-851a34f4 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-851a34f4{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-851a34f4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-851a34f4{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-a397766d.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-a397766d.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a397766d.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a397766d.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-a77cae6b .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a77cae6b .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a77cae6b .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a77cae6b .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a77cae6b .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a77cae6b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a77cae6b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-a77cae6b.uagb-layout-grid > .uagb-container-inner-blocks-wrap{row-gap: 20px;column-gap: 20px;grid-template-columns: minmax( 1px, 1fr)  minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-a77cae6b{min-height: 400px;box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;}.wp-block-uagb-container.uagb-block-eaf03854 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-eaf03854 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-eaf03854 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-eaf03854 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-eaf03854 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-eaf03854{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-eaf03854 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-eaf03854{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-6e502311.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-6e502311.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-6e502311.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-6e502311.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-75ab9cfa .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-75ab9cfa .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-75ab9cfa .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-75ab9cfa .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-75ab9cfa .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-75ab9cfa{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-75ab9cfa > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-75ab9cfa{min-height: 300px;box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-18c6690d.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-18c6690d.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-18c6690d.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-18c6690d.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-18c6690d.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-18c6690d .uagb-heading-text{font-size: 7em;}.wp-block-uagb-container.uagb-block-b5dc6176 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b5dc6176 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b5dc6176 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b5dc6176 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b5dc6176 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b5dc6176{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b5dc6176 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-b5dc6176.uagb-layout-grid > .uagb-container-inner-blocks-wrap{row-gap: 20px;column-gap: 20px;grid-template-columns: minmax( 1px, 1fr)  minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-b5dc6176{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;}.wp-block-uagb-container.uagb-block-25ed64b4 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-25ed64b4 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-25ed64b4 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-25ed64b4 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-25ed64b4 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-25ed64b4{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-25ed64b4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-25ed64b4{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-09816bf8.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-09816bf8.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-09816bf8.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-09816bf8.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.uagb-block-b98a8859 .uagb-icon svg{width: 12px;height: 12px;font-size: 12px;}.uagb-block-b98a8859 .uagb-icon-active svg{width: 12px;height: 12px;font-size: 12px;}.uagb-block-b98a8859 .uagb-faq-child__outer-wrap{margin-bottom: 10px;}.uagb-block-b98a8859 .uagb-faq-item{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 2px;border-top-right-radius: 2px;border-bottom-left-radius: 2px;border-bottom-right-radius: 2px;border-color: #D2D2D2;border-style: solid;}.uagb-block-b98a8859 .uagb-faq-questions-button{padding-top: 10px;padding-bottom: 10px;padding-right: 10px;padding-left: 10px;}.uagb-block-b98a8859 .uagb-faq-content{padding-top: 10px;padding-bottom: 10px;padding-right: 10px;padding-left: 10px;}.uagb-block-b98a8859 .uagb-faq-content span{margin-top: 10px;margin-bottom: 10px;margin-right: 10px;margin-left: 10px;}.uagb-block-b98a8859.uagb-faq-icon-row .uagb-faq-item .uagb-faq-icon-wrap{margin-right: 10px;}.uagb-block-b98a8859.uagb-faq-icon-row-reverse .uagb-faq-item .uagb-faq-icon-wrap{margin-left: 10px;}.uagb-block-b98a8859 .uagb-faq-item .uagb-faq-questions-button.uagb-faq-questions{flex-direction: row;}.uagb-block-b98a8859 .wp-block-uagb-faq-child.uagb-faq-child__outer-wrap .uagb-faq-content {display: none;}.wp-block-uagb-container.uagb-block-52483083 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-52483083 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-52483083 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-52483083 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-52483083 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-52483083{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-52483083 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-52483083{min-height: 400px;box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 50% 50%;background-size: contain;background-attachment: scroll;background-image: url(https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/04\/Track-Anything-and-Everything.png);background-clip: padding-box;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-2bcb69f4 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2bcb69f4 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2bcb69f4 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2bcb69f4 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2bcb69f4 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2bcb69f4{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2bcb69f4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-2bcb69f4.uagb-layout-grid > .uagb-container-inner-blocks-wrap{row-gap: 20px;column-gap: 20px;grid-template-columns: minmax( 1px, 1fr)  minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-2bcb69f4{min-height: 400px;box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;}.wp-block-uagb-container.uagb-block-46d3c6b5 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-46d3c6b5 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-46d3c6b5 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-46d3c6b5 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-46d3c6b5 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-46d3c6b5{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-46d3c6b5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-46d3c6b5{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-8f9b2c3a.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-8f9b2c3a.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8f9b2c3a.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8f9b2c3a.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-489a6b22 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-489a6b22 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-489a6b22 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-489a6b22 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-489a6b22 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-489a6b22{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-489a6b22 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-489a6b22{min-height: 300px;box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 50% 50%;background-size: contain;background-attachment: scroll;background-image: url(https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/04\/on-board-processing-2x-800x487-1.webp);background-clip: padding-box;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-7f5140e3.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-7f5140e3.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-7f5140e3.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7f5140e3.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7f5140e3.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7f5140e3.wp-block-uagb-advanced-heading .uagb-separator{border-top-style: solid;border-top-width: 2px;width: 12%;border-color: var(--ast-global-color-0);margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-7f5140e3 .uagb-heading-text{margin-bottom: 15px;}.wp-block-uagb-container.uagb-block-acda9497 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-acda9497 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-acda9497 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-acda9497 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-acda9497 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-acda9497{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-acda9497 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-acda9497.uagb-layout-grid > .uagb-container-inner-blocks-wrap{row-gap: 20px;column-gap: 20px;grid-template-columns: minmax( 1px, 1fr)  minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-acda9497{min-height: 400px;box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;}.wp-block-uagb-container.uagb-block-9beaa52c .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9beaa52c .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9beaa52c .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9beaa52c .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9beaa52c .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9beaa52c{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9beaa52c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-9beaa52c{min-height: 300px;box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 50% 50%;background-size: contain;background-attachment: scroll;background-image: url(https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/04\/stretch2-900-800x799-1.webp);background-clip: padding-box;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-249a2b37 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-249a2b37 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-249a2b37 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-249a2b37 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-249a2b37 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-249a2b37{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-249a2b37 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-249a2b37{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-f129f270.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-f129f270.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f129f270.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f129f270.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-5e6af294 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5e6af294 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5e6af294 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5e6af294 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5e6af294 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5e6af294{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5e6af294 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-5e6af294.uagb-layout-grid > .uagb-container-inner-blocks-wrap{row-gap: 20px;column-gap: 20px;grid-template-columns: minmax( 1px, 1fr)  minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-5e6af294{min-height: 400px;box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;}.wp-block-uagb-container.uagb-block-b12c1033 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b12c1033 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b12c1033 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b12c1033 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b12c1033 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b12c1033{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b12c1033 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-b12c1033{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-85d0c948.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-85d0c948.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-85d0c948.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-85d0c948.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-f8bac439 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f8bac439 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f8bac439 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f8bac439 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f8bac439 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f8bac439{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f8bac439 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-f8bac439{min-height: 300px;box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 50% 50%;background-size: contain;background-attachment: scroll;background-image: url(https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/04\/camerasdk-monitor-2x.webp);background-clip: padding-box;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-c5586b9c .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c5586b9c .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c5586b9c .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c5586b9c .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c5586b9c .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c5586b9c{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c5586b9c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-c5586b9c.uagb-layout-grid > .uagb-container-inner-blocks-wrap{row-gap: 20px;column-gap: 20px;grid-template-columns: minmax( 1px, 1fr)  minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-c5586b9c{min-height: 400px;box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;}.wp-block-uagb-container.uagb-block-61226197 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-61226197 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-61226197 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-61226197 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-61226197 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-61226197{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-61226197 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-61226197{min-height: 300px;box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 50% 50%;background-size: contain;background-attachment: scroll;background-image: url(https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/04\/external-sync-camera-2x-1.webp);background-clip: padding-box;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-5487f77b .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5487f77b .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5487f77b .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5487f77b .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5487f77b .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5487f77b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5487f77b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-5487f77b{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-5239e430.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-5239e430.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-5239e430.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-5239e430.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-d0d3b0df .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d0d3b0df .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d0d3b0df .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d0d3b0df .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d0d3b0df .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d0d3b0df{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d0d3b0df > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-d0d3b0df.uagb-layout-grid > .uagb-container-inner-blocks-wrap{row-gap: 20px;column-gap: 20px;grid-template-columns: minmax( 1px, 1fr)  minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-d0d3b0df{min-height: 400px;box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;}.wp-block-uagb-container.uagb-block-573db6ef .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-573db6ef .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-573db6ef .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-573db6ef .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-573db6ef .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-573db6ef{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-573db6ef > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-573db6ef{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-d153fd52.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-d153fd52.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-d153fd52.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-d153fd52.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-d9da6336 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d9da6336 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d9da6336 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d9da6336 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d9da6336 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d9da6336{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d9da6336 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-d9da6336{min-height: 300px;box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 50% 50%;background-size: contain;background-attachment: scroll;background-image: url(https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/04\/active-passive-2x.webp);background-clip: padding-box;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-9ee31919 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9ee31919 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9ee31919 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9ee31919 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9ee31919 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9ee31919{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9ee31919 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-9ee31919.uagb-layout-grid > .uagb-container-inner-blocks-wrap{row-gap: 20px;column-gap: 20px;grid-template-columns: minmax( 1px, 1fr)  minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-9ee31919{min-height: 400px;box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;}.wp-block-uagb-container.uagb-block-a0f51320 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a0f51320 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a0f51320 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a0f51320 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a0f51320 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a0f51320{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a0f51320 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-a0f51320{min-height: 300px;box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 50% 50%;background-size: contain;background-attachment: scroll;background-image: url(https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/04\/mix-and-match-cameras-2x-800x450-1.webp);background-clip: padding-box;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-3a3cf7db .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3a3cf7db .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3a3cf7db .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3a3cf7db .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3a3cf7db .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3a3cf7db{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3a3cf7db > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-3a3cf7db{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-e9ba948a.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-e9ba948a.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e9ba948a.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e9ba948a.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-ad6b2a76 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ad6b2a76 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ad6b2a76 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ad6b2a76 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ad6b2a76 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ad6b2a76{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ad6b2a76 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-ad6b2a76.uagb-layout-grid > .uagb-container-inner-blocks-wrap{row-gap: 20px;column-gap: 20px;grid-template-columns: minmax( 1px, 1fr)  minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-ad6b2a76{min-height: 400px;box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;}.wp-block-uagb-container.uagb-block-2e04eb07 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2e04eb07 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2e04eb07 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2e04eb07 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2e04eb07 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2e04eb07{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2e04eb07 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-2e04eb07{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-7fef2a0e.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-7fef2a0e.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7fef2a0e.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7fef2a0e.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-50af0eb4 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-50af0eb4 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-50af0eb4 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-50af0eb4 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-50af0eb4 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-50af0eb4{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-50af0eb4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-50af0eb4 .uagb-container__video-wrap{border-color: inherit;}.wp-block-uagb-container.uagb-block-50af0eb4 > div:not(.uagb-container__video-wrap):not(.uagb-container__shape){position: relative;}.wp-block-uagb-container.wp-block-uagb-container.uagb-block-50af0eb4{flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-50af0eb4{min-height: 300px;box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;row-gap: 20px;column-gap: 20px;overflow: visible;}.wp-block-uagb-container.uagb-block-cd025ccc .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-cd025ccc .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-cd025ccc .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-cd025ccc .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-cd025ccc .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-cd025ccc{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-cd025ccc > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-cd025ccc.uagb-layout-grid > .uagb-container-inner-blocks-wrap{row-gap: 20px;column-gap: 20px;grid-template-columns: minmax( 1px, 75%)  minmax( 1px, 25%) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-cd025ccc{min-height: 500px;box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;}.wp-block-uagb-container.uagb-block-faaef517 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-faaef517 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-faaef517 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-faaef517 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-faaef517 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-faaef517{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-faaef517 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-faaef517 .uagb-container__video-wrap{border-color: inherit;}.wp-block-uagb-container.uagb-block-faaef517 > div:not(.uagb-container__video-wrap):not(.uagb-container__shape){position: relative;}.wp-block-uagb-container.wp-block-uagb-container.uagb-block-faaef517{flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-faaef517{min-height: 300px;box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;row-gap: 20px;column-gap: 20px;overflow: visible;}.wp-block-uagb-container.uagb-block-2946affe .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2946affe .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2946affe .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2946affe .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2946affe .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2946affe{max-width: 100px;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2946affe > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-2946affe{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-a30d811c.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-a30d811c.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a30d811c.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a30d811c.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.uagb-block-9fda86f2.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-9fda86f2.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.wp-block-uagb-buttons .uagb-block-867181e8 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-867181e8 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-867181e8 .uagb-buttons-repeater.wp-block-button__link{border-color: #333;border-style: none;}.wp-block-uagb-buttons .uagb-block-867181e8 .uagb-buttons-repeater.wp-block-button__link:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-867181e8 .uagb-buttons-repeater.wp-block-button__link:focus{border-color: #333;}.wp-block-uagb-buttons .uagb-block-867181e8.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-color: #333;border-style: none;}.wp-block-uagb-buttons .uagb-block-867181e8.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-867181e8 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;}.wp-block-uagb-buttons .uagb-block-867181e8 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-867181e8 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-buttons .uagb-block-867181e8 .uagb-button__link{text-transform: normal;text-decoration: none;}.wp-block-uagb-container.uagb-block-46e52077 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-46e52077 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-46e52077 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-46e52077 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-46e52077 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-46e52077{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-46e52077 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-46e52077{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-03d0b952 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-03d0b952 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-03d0b952 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-03d0b952 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-03d0b952 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-03d0b952{max-width: 5%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-03d0b952 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-03d0b952{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-8bfd2a35 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-8bfd2a35 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-8bfd2a35 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-8bfd2a35 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-8bfd2a35 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8bfd2a35{max-width: 95%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8bfd2a35 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-8bfd2a35{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-c2a6af6f .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c2a6af6f .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c2a6af6f .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c2a6af6f .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c2a6af6f .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c2a6af6f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c2a6af6f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-c2a6af6f{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-9ad863ad .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9ad863ad .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9ad863ad .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9ad863ad .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9ad863ad .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9ad863ad{max-width: 5%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9ad863ad > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-9ad863ad{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-03e85a84 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-03e85a84 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-03e85a84 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-03e85a84 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-03e85a84 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-03e85a84{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-03e85a84 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-03e85a84{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-33209cc4 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-33209cc4 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-33209cc4 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-33209cc4 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-33209cc4 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-33209cc4{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-33209cc4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-33209cc4{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-87a11183.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-87a11183.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-87a11183.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-87a11183.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-87a11183.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-87a11183.wp-block-uagb-advanced-heading .uagb-separator{border-top-style: solid;border-top-width: 2px;width: 12%;border-color: var(--ast-global-color-0);margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-87a11183 .uagb-heading-text{margin-bottom: 15px;}.wp-block-uagb-container.uagb-block-5f32531b .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5f32531b .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5f32531b .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5f32531b .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5f32531b .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5f32531b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5f32531b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-5f32531b{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-09341d66 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-09341d66 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-09341d66 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-09341d66 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-09341d66 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-09341d66{max-width: 25%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-09341d66 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-09341d66{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-c98f029a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c98f029a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c98f029a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c98f029a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c98f029a .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c98f029a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c98f029a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-c98f029a{min-height: 150px;box-shadow: 3px 8px 12px 0px #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-left-radius: 15px;border-top-right-radius: 15px;border-bottom-left-radius: 15px;border-bottom-right-radius: 15px;border-color: inherit;background-color: var(--ast-global-color-5);;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-c98f029a:hover{box-shadow: 0px 0px 0px 0px  ;}.uagb-block-15fc2204 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-15fc2204 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: var(--ast-global-color-0);}.uagb-block-15fc2204 .uagb-ifb-icon svg{fill: var(--ast-global-color-0);}.uagb-block-15fc2204.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-15fc2204 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-15fc2204 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-15fc2204.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-15fc2204.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-15fc2204 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-15fc2204 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-15fc2204 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-15fc2204 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-15fc2204.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-15fc2204.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-15fc2204.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-15fc2204.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-15fc2204 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-15fc2204 .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-15fc2204 .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-15fc2204 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-15fc2204 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-15fc2204 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-15fc2204 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-15fc2204.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-15fc2204.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-15fc2204 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-15fc2204.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-15fc2204.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-15fc2204 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-15fc2204.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-15fc2204.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-15fc2204.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-15fc2204.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-15fc2204.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-15fc2204.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-15fc2204.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-15fc2204.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-15fc2204.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-ae569a76 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ae569a76 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ae569a76 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ae569a76 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ae569a76 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ae569a76{max-width: 25%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ae569a76 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-ae569a76{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-d119f077 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d119f077 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d119f077 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d119f077 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d119f077 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d119f077{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d119f077 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-d119f077{min-height: 150px;box-shadow: 3px 8px 12px 0px #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-left-radius: 15px;border-top-right-radius: 15px;border-bottom-left-radius: 15px;border-bottom-right-radius: 15px;border-color: inherit;background-color: var(--ast-global-color-5);;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-d119f077:hover{box-shadow: 0px 0px 0px 0px  ;}.uagb-block-4482f584 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-4482f584 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: var(--ast-global-color-0);}.uagb-block-4482f584 .uagb-ifb-icon svg{fill: var(--ast-global-color-0);}.uagb-block-4482f584.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-4482f584 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-4482f584 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-4482f584.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-4482f584.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-4482f584 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-4482f584 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-4482f584 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-4482f584 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-4482f584.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-4482f584.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-4482f584.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-4482f584.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-4482f584 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-4482f584 .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-4482f584 .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-4482f584 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-4482f584 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-4482f584 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-4482f584 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-4482f584.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-4482f584.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-4482f584 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-4482f584.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-4482f584.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-4482f584 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4482f584.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4482f584.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4482f584.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4482f584.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4482f584.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4482f584.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4482f584.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-4482f584.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-4482f584.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-81d10344 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-81d10344 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-81d10344 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-81d10344 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-81d10344 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-81d10344{max-width: 25%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-81d10344 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-81d10344{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-e6f7e635 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e6f7e635 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e6f7e635 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e6f7e635 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e6f7e635 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e6f7e635{max-width: 25%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e6f7e635 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-e6f7e635{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-5ed88e67 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5ed88e67 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5ed88e67 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5ed88e67 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5ed88e67 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5ed88e67{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5ed88e67 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-5ed88e67{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-13bf796f.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-13bf796f.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-13bf796f.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-13bf796f.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-13bf796f.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-13bf796f.wp-block-uagb-advanced-heading .uagb-separator{border-top-style: solid;border-top-width: 2px;width: 12%;border-color: var(--ast-global-color-0);margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-13bf796f .uagb-heading-text{margin-bottom: 15px;}.uagb-block-5c866cf4.uagb-loop-container{flex-direction: row;gap: 24px;}.uagb-block-5c866cf4.uagb-loop-container > .uagb-loop-post{width: calc( calc(100% - 3 * 24px ) \/ 4 );}.wp-block-uagb-container.uagb-block-0a6d8384 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-0a6d8384 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-0a6d8384 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-0a6d8384 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-0a6d8384 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0a6d8384{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-0a6d8384{min-height: 500px;box-shadow: 0px 0px 12px 0px #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-left-radius: 15px;border-top-right-radius: 15px;border-bottom-left-radius: 15px;border-bottom-right-radius: 15px;border-color: inherit;background-color: var(--ast-global-color-5);;flex-direction: column;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-0a6d8384:hover{box-shadow: 0px 0px 0px 0px  ;}.uagb-block-157e55c8.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 16px;margin-left: 0px;}.uagb-block-157e55c8.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 15px;border-top-right-radius: 15px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;}.uagb-block-157e55c8.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-157e55c8.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 15px;border-top-right-radius: 15px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;}.uagb-block-157e55c8.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 15px;border-top-right-radius: 15px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;}.uagb-block-157e55c8.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-157e55c8.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-157e55c8.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-157e55c8.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-157e55c8.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-157e55c8.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-157e55c8.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 1200px;height: 200px;}.uagb-block-157e55c8.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-157e55c8.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-157e55c8.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-157e55c8.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-advanced-heading.uagb-block-dfc003ee.wp-block-uagb-advanced-heading {padding-top: 6px;padding-right: 10px;padding-bottom: 12px;padding-left: 10px;}.wp-block-uagb-advanced-heading.uagb-block-dfc003ee.wp-block-uagb-advanced-heading a{color: var(--ast-global-color-2);}.wp-block-uagb-advanced-heading.uagb-block-dfc003ee.wp-block-uagb-advanced-heading a:hover{color: var(--ast-global-color-0);}.wp-block-uagb-advanced-heading.uagb-block-dfc003ee.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-dfc003ee.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: var(--ast-global-color-0);color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-dfc003ee.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: var(--ast-global-color-0);-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-dfc003ee.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: var(--ast-global-color-0);-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-17b75880.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-1);}.wp-block-uagb-advanced-heading.uagb-block-17b75880.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 10px;padding-bottom: 0px;padding-left: 10px;}.wp-block-uagb-advanced-heading.uagb-block-17b75880.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-17b75880.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-17b75880.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-17b75880.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-17b75880 .uagb-heading-text{font-size: 1em;}.uagb-block-0f1b5f2d.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-0f1b5f2d.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-0f1b5f2d .uagb-buttons-repeater:not(.wp-block-button__link){padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;}.uagb-block-0f1b5f2d .uagb-button__wrapper .uagb-buttons-repeater.wp-block-button__link{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;}.uagb-block-0f1b5f2d .uagb-button__wrapper .uagb-buttons-repeater.ast-outline-button{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;}.uagb-block-0f1b5f2d .uagb-button__wrapper{margin-top: 19px;margin-bottom: 19px;margin-left: 19px;margin-right: 19px;}.wp-block-uagb-buttons .uagb-block-d6ad2265 .uagb-button__wrapper .uagb-buttons-repeater{padding-top: 15px;padding-bottom: 15px;padding-left: 30px;padding-right: 30px;color: #ffffff;margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;}.wp-block-uagb-buttons .uagb-block-d6ad2265 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-d6ad2265 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-d6ad2265 .uagb-buttons-repeater.wp-block-button__link{border-top-width: 0px;border-left-width: 0px;border-right-width: 0px;border-bottom-width: 0px;border-top-left-radius: 15px;border-top-right-radius: 15px;border-bottom-left-radius: 15px;border-bottom-right-radius: 15px;border-style: solid;}.wp-block-uagb-buttons .uagb-block-d6ad2265 .uagb-buttons-repeater.wp-block-button__link:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-d6ad2265 .uagb-buttons-repeater.wp-block-button__link:focus{border-color: #333;}.wp-block-uagb-buttons .uagb-block-d6ad2265.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-top-width: 0px;border-left-width: 0px;border-right-width: 0px;border-bottom-width: 0px;border-top-left-radius: 15px;border-top-right-radius: 15px;border-bottom-left-radius: 15px;border-bottom-right-radius: 15px;border-style: solid;}.wp-block-uagb-buttons .uagb-block-d6ad2265.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-d6ad2265 .uagb-buttons-repeater .uagb-button__link{color: #ffffff;}.wp-block-uagb-buttons .uagb-block-d6ad2265 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: #ffffff;}.wp-block-uagb-buttons .uagb-block-d6ad2265 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-d6ad2265 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-buttons .uagb-block-d6ad2265 .uagb-button__link{text-transform: normal;text-decoration: none;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-c37632dd{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c37632dd > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-c37632dd{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-4);;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8160c408{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8160c408 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-8160c408{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-57b573d8{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-57b573d8 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-57b573d8{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-efb600c6.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-efb600c6.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-6c86d97c.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: none;border-color: #333;}.wp-block-uagb-buttons .uagb-block-6c86d97c .uagb-buttons-repeater.wp-block-button__link{border-style: none;border-color: #333;}.wp-block-uagb-buttons .uagb-block-8368e105 .wp-block-button__link:hover{background: ;;background-clip: padding-box;}.wp-block-uagb-buttons .uagb-block-8368e105 .wp-block-button__link:focus{background: ;;background-clip: padding-box;}.wp-block-uagb-buttons .uagb-block-8368e105.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: none;border-color: #333;}.wp-block-uagb-buttons .uagb-block-8368e105 .uagb-buttons-repeater.wp-block-button__link{border-style: none;border-color: #333;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-217fd5a5{width: 100%;}.wp-block-uagb-container.uagb-block-217fd5a5{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/04\/primex22-hero-desktop-v2-2000x600-1.jpg);background-clip: padding-box;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-49ad00df{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-49ad00df > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-49ad00df.uagb-layout-grid{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-49ad00df{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-01a5ec31{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-01a5ec31 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-01a5ec31{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-98b90e67{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-98b90e67 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-98b90e67{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-24eed835.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-24eed835.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-24eed835.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-24eed835 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-24eed835 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-24eed835 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-24eed835 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-24eed835 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-24eed835.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-24eed835.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-58da930d{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-58da930d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-58da930d{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-f79d1186.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-f79d1186.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-f79d1186.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-f79d1186 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-f79d1186 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-f79d1186 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-f79d1186 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-f79d1186 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-f79d1186.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-f79d1186.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-39ee6f6a{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-39ee6f6a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-39ee6f6a{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-4ab4d9d6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-4ab4d9d6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-4ab4d9d6.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-4ab4d9d6 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-4ab4d9d6 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-4ab4d9d6 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-4ab4d9d6 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-4ab4d9d6 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-4ab4d9d6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-4ab4d9d6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a2f6c5e0{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a2f6c5e0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-a2f6c5e0{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-32bcbeda.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-32bcbeda.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-32bcbeda.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-32bcbeda .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-32bcbeda .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-32bcbeda .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-32bcbeda .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-32bcbeda .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-32bcbeda.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-32bcbeda.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-80b095e0{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-80b095e0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-80b095e0.uagb-layout-grid > .uagb-container-inner-blocks-wrap{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-80b095e0{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5b5f2cd6{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5b5f2cd6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-5b5f2cd6{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0b1e3dc1{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0b1e3dc1 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-0b1e3dc1{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/05\/marys-peak-square-2049-2000x2000-1.png);background-clip: padding-box;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-863cfced{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-863cfced > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-863cfced.uagb-layout-grid > .uagb-container-inner-blocks-wrap{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-863cfced{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c7d62716{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c7d62716 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-c7d62716{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/05\/prime22-elegant-design.webp);background-clip: padding-box;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e7f3e310{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e7f3e310 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-e7f3e310{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ce0a037a{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ce0a037a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-ce0a037a.uagb-layout-grid > .uagb-container-inner-blocks-wrap{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-ce0a037a{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3ae92481{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3ae92481 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-3ae92481{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9f65af31{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9f65af31 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-9f65af31{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-eb5bd218{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-eb5bd218 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-eb5bd218.uagb-layout-grid > .uagb-container-inner-blocks-wrap{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-eb5bd218{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-42748acf{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-42748acf > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-42748acf{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/05\/prime22-fast-glass-2x.webp);background-clip: padding-box;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a5cf6412{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a5cf6412 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-a5cf6412{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ba971622{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ba971622 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-ba971622.uagb-layout-grid > .uagb-container-inner-blocks-wrap{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-ba971622{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-eef5b719{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-eef5b719 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-eef5b719{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5074e906{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5074e906 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-5074e906{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/05\/prime22-wide-angle-2x-800x600-1.webp);background-clip: padding-box;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4a753c21{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4a753c21 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-4a753c21.uagb-layout-grid > .uagb-container-inner-blocks-wrap{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-4a753c21{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4d6e79c8{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4d6e79c8 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-4d6e79c8{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/04\/on-board-processing-2x-800x487-1.webp);background-clip: padding-box;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-851a34f4{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-851a34f4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-851a34f4{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a77cae6b{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a77cae6b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-a77cae6b.uagb-layout-grid > .uagb-container-inner-blocks-wrap{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-a77cae6b{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-eaf03854{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-eaf03854 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-eaf03854{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-75ab9cfa{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-75ab9cfa > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-75ab9cfa{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b5dc6176{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b5dc6176 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-b5dc6176.uagb-layout-grid > .uagb-container-inner-blocks-wrap{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-b5dc6176{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-25ed64b4{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-25ed64b4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-25ed64b4{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.uagb-block-b98a8859.uagb-faq-icon-row .uagb-faq-item .uagb-faq-icon-wrap{margin-right: 10px;}.uagb-block-b98a8859.uagb-faq-icon-row-reverse .uagb-faq-item .uagb-faq-icon-wrap{margin-left: 10px;}.uagb-block-b98a8859 .uagb-faq-questions-button{padding-top: 10px;padding-bottom: 10px;padding-right: 10px;padding-left: 10px;}.uagb-block-b98a8859 .uagb-faq-content{padding-top: 10px;padding-bottom: 10px;padding-right: 10px;padding-left: 10px;}.uagb-block-b98a8859 .uagb-faq-content span{margin-top: 10px;margin-bottom: 10px;margin-right: 10px;margin-left: 10px;}.uagb-block-b98a8859 .uagb-faq-item{border-style: solid;border-color: #D2D2D2;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-52483083{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-52483083 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-52483083{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/04\/Track-Anything-and-Everything.png);background-clip: padding-box;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2bcb69f4{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2bcb69f4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-2bcb69f4.uagb-layout-grid > .uagb-container-inner-blocks-wrap{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-2bcb69f4{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-46d3c6b5{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-46d3c6b5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-46d3c6b5{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-489a6b22{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-489a6b22 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-489a6b22{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/04\/on-board-processing-2x-800x487-1.webp);background-clip: padding-box;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-acda9497{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-acda9497 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-acda9497.uagb-layout-grid > .uagb-container-inner-blocks-wrap{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-acda9497{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9beaa52c{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9beaa52c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-9beaa52c{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/04\/stretch2-900-800x799-1.webp);background-clip: padding-box;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-249a2b37{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-249a2b37 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-249a2b37{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5e6af294{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5e6af294 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-5e6af294.uagb-layout-grid > .uagb-container-inner-blocks-wrap{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-5e6af294{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b12c1033{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b12c1033 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-b12c1033{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f8bac439{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f8bac439 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-f8bac439{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/04\/camerasdk-monitor-2x.webp);background-clip: padding-box;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c5586b9c{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c5586b9c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-c5586b9c.uagb-layout-grid > .uagb-container-inner-blocks-wrap{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-c5586b9c{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-61226197{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-61226197 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-61226197{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/04\/external-sync-camera-2x-1.webp);background-clip: padding-box;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5487f77b{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5487f77b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-5487f77b{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d0d3b0df{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d0d3b0df > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-d0d3b0df.uagb-layout-grid > .uagb-container-inner-blocks-wrap{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-d0d3b0df{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-573db6ef{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-573db6ef > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-573db6ef{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d9da6336{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d9da6336 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-d9da6336{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/04\/active-passive-2x.webp);background-clip: padding-box;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9ee31919{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9ee31919 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-9ee31919.uagb-layout-grid > .uagb-container-inner-blocks-wrap{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-9ee31919{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a0f51320{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a0f51320 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-a0f51320{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/04\/mix-and-match-cameras-2x-800x450-1.webp);background-clip: padding-box;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3a3cf7db{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3a3cf7db > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-3a3cf7db{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ad6b2a76{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ad6b2a76 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-ad6b2a76.uagb-layout-grid > .uagb-container-inner-blocks-wrap{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-ad6b2a76{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2e04eb07{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2e04eb07 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-2e04eb07{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-50af0eb4{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-50af0eb4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-50af0eb4{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-cd025ccc{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-cd025ccc > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-cd025ccc.uagb-layout-grid > .uagb-container-inner-blocks-wrap{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-cd025ccc{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-faaef517{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-faaef517 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-faaef517{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2946affe{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2946affe > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-2946affe{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.uagb-block-9fda86f2.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-9fda86f2.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-867181e8.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: none;border-color: #333;}.wp-block-uagb-buttons .uagb-block-867181e8 .uagb-buttons-repeater.wp-block-button__link{border-style: none;border-color: #333;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-46e52077{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-46e52077 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-46e52077{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-03d0b952{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-03d0b952 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-03d0b952{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8bfd2a35{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8bfd2a35 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-8bfd2a35{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c2a6af6f{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c2a6af6f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-c2a6af6f{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9ad863ad{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9ad863ad > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-9ad863ad{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-03e85a84{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-03e85a84 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-03e85a84{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-33209cc4{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-33209cc4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-33209cc4{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5f32531b{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5f32531b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-5f32531b{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-09341d66{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-09341d66 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-09341d66{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c98f029a{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c98f029a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-c98f029a{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-5);;}.uagb-block-15fc2204.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-15fc2204.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-15fc2204.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-15fc2204 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-15fc2204 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-15fc2204 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-15fc2204 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-15fc2204 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-15fc2204.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-15fc2204.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ae569a76{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ae569a76 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-ae569a76{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d119f077{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d119f077 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-d119f077{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-5);;}.uagb-block-4482f584.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-4482f584.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-4482f584.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-4482f584 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-4482f584 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-4482f584 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-4482f584 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-4482f584 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-4482f584.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-4482f584.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-81d10344{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-81d10344 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-81d10344{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e6f7e635{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e6f7e635 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-e6f7e635{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5ed88e67{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5ed88e67 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-5ed88e67{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-5c866cf4.uagb-loop-container{flex-direction: row;gap: 24px;}.uagb-block-5c866cf4.uagb-loop-container > .uagb-loop-post{width: calc( calc(100% - 1 * 24px ) \/ 2 );}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0a6d8384{width: 100%;}.wp-block-uagb-container.uagb-block-0a6d8384{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-5);;align-items: flex-start;justify-content: flex-start;}.uagb-block-157e55c8.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 1200px;height: auto;}.uagb-block-0f1b5f2d.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-0f1b5f2d.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-d6ad2265.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;}.wp-block-uagb-buttons .uagb-block-d6ad2265 .uagb-buttons-repeater.wp-block-button__link{border-style: solid;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-c37632dd{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c37632dd > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-c37632dd{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-4);;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8160c408{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8160c408 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-8160c408{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-57b573d8{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-57b573d8 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-57b573d8{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-efb600c6.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-efb600c6.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-6c86d97c.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: none;border-color: #333;}.wp-block-uagb-buttons .uagb-block-6c86d97c .uagb-buttons-repeater.wp-block-button__link{border-style: none;border-color: #333;}.wp-block-uagb-buttons .uagb-block-8368e105 .wp-block-button__link:hover{background: ;;background-clip: padding-box;}.wp-block-uagb-buttons .uagb-block-8368e105 .wp-block-button__link:focus{background: ;;background-clip: padding-box;}.wp-block-uagb-buttons .uagb-block-8368e105.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: none;border-color: #333;}.wp-block-uagb-buttons .uagb-block-8368e105 .uagb-buttons-repeater.wp-block-button__link{border-style: none;border-color: #333;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-217fd5a5{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-217fd5a5{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/04\/primex22-hero-desktop-v2-2000x600-1.jpg);background-clip: padding-box;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-49ad00df{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-49ad00df > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-49ad00df.uagb-layout-grid{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-49ad00df{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-01a5ec31{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-01a5ec31 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-01a5ec31{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-98b90e67{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-98b90e67 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-98b90e67{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-24eed835.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-24eed835.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-24eed835 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-24eed835 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-24eed835.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-24eed835 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-24eed835 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-24eed835 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-24eed835.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-24eed835.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-58da930d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-58da930d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-58da930d{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-f79d1186.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-f79d1186.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-f79d1186 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-f79d1186 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-f79d1186.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-f79d1186 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-f79d1186 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-f79d1186 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-f79d1186.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-f79d1186.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-39ee6f6a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-39ee6f6a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-39ee6f6a{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-4ab4d9d6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-4ab4d9d6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-4ab4d9d6 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-4ab4d9d6 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-4ab4d9d6.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-4ab4d9d6 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-4ab4d9d6 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-4ab4d9d6 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-4ab4d9d6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-4ab4d9d6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a2f6c5e0{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a2f6c5e0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-a2f6c5e0{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-32bcbeda.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-32bcbeda.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-32bcbeda .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-32bcbeda .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-32bcbeda.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-32bcbeda .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-32bcbeda .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-32bcbeda .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-32bcbeda.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-32bcbeda.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-80b095e0{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-80b095e0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-80b095e0.uagb-layout-grid > .uagb-container-inner-blocks-wrap{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-80b095e0{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5b5f2cd6{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5b5f2cd6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-5b5f2cd6{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0b1e3dc1{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0b1e3dc1 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-0b1e3dc1{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/05\/marys-peak-square-2049-2000x2000-1.png);background-clip: padding-box;flex-wrap: wrap;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-863cfced{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-863cfced > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-863cfced.uagb-layout-grid > .uagb-container-inner-blocks-wrap{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-863cfced{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c7d62716{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c7d62716 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-c7d62716{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/05\/prime22-elegant-design.webp);background-clip: padding-box;flex-wrap: wrap;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e7f3e310{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e7f3e310 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-e7f3e310{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ce0a037a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ce0a037a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-ce0a037a.uagb-layout-grid > .uagb-container-inner-blocks-wrap{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-ce0a037a{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3ae92481{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3ae92481 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-3ae92481{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9f65af31{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9f65af31 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.wp-block-uagb-container.uagb-block-9f65af31{flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-9f65af31{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-eb5bd218{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-eb5bd218 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-eb5bd218.uagb-layout-grid > .uagb-container-inner-blocks-wrap{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-eb5bd218{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-42748acf{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-42748acf > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-42748acf{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/05\/prime22-fast-glass-2x.webp);background-clip: padding-box;flex-wrap: wrap;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a5cf6412{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a5cf6412 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-a5cf6412{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ba971622{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ba971622 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-ba971622.uagb-layout-grid > .uagb-container-inner-blocks-wrap{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-ba971622{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-eef5b719{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-eef5b719 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-eef5b719{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5074e906{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5074e906 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-5074e906{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/05\/prime22-wide-angle-2x-800x600-1.webp);background-clip: padding-box;flex-wrap: wrap;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4a753c21{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4a753c21 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-4a753c21.uagb-layout-grid > .uagb-container-inner-blocks-wrap{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-4a753c21{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4d6e79c8{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4d6e79c8 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-4d6e79c8{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/04\/on-board-processing-2x-800x487-1.webp);background-clip: padding-box;flex-wrap: wrap;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-851a34f4{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-851a34f4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-851a34f4{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a77cae6b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a77cae6b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-a77cae6b.uagb-layout-grid > .uagb-container-inner-blocks-wrap{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-a77cae6b{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-eaf03854{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-eaf03854 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-eaf03854{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-75ab9cfa{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-75ab9cfa > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-75ab9cfa{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b5dc6176{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b5dc6176 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-b5dc6176.uagb-layout-grid > .uagb-container-inner-blocks-wrap{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-b5dc6176{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-25ed64b4{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-25ed64b4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-25ed64b4{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.uagb-block-b98a8859.uagb-faq-icon-row .uagb-faq-item .uagb-faq-icon-wrap{margin-right: 10px;}.uagb-block-b98a8859 .uagb-faq-item{border-style: solid;border-color: #D2D2D2;}.uagb-block-b98a8859.uagb-faq-icon-row-reverse .uagb-faq-item .uagb-faq-icon-wrap{margin-left: 10px;}.uagb-block-b98a8859 .uagb-faq-questions-button{padding-top: 10px;padding-bottom: 10px;padding-right: 10px;padding-left: 10px;}.uagb-block-b98a8859 .uagb-faq-content{padding-top: 10px;padding-bottom: 10px;padding-right: 10px;padding-left: 10px;}.uagb-block-b98a8859 .uagb-faq-content span{margin-top: 10px;margin-bottom: 10px;margin-right: 10px;margin-left: 10px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-52483083{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-52483083 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-52483083{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/04\/Track-Anything-and-Everything.png);background-clip: padding-box;flex-wrap: wrap;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2bcb69f4{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2bcb69f4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-2bcb69f4.uagb-layout-grid > .uagb-container-inner-blocks-wrap{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-2bcb69f4{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-46d3c6b5{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-46d3c6b5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-46d3c6b5{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-489a6b22{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-489a6b22 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-489a6b22{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/04\/on-board-processing-2x-800x487-1.webp);background-clip: padding-box;flex-wrap: wrap;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-acda9497{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-acda9497 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-acda9497.uagb-layout-grid > .uagb-container-inner-blocks-wrap{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-acda9497{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9beaa52c{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9beaa52c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-9beaa52c{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/04\/stretch2-900-800x799-1.webp);background-clip: padding-box;flex-wrap: wrap;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-249a2b37{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-249a2b37 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-249a2b37{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5e6af294{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5e6af294 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-5e6af294.uagb-layout-grid > .uagb-container-inner-blocks-wrap{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-5e6af294{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b12c1033{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b12c1033 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-b12c1033{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f8bac439{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f8bac439 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-f8bac439{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/04\/camerasdk-monitor-2x.webp);background-clip: padding-box;flex-wrap: wrap;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c5586b9c{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c5586b9c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-c5586b9c.uagb-layout-grid > .uagb-container-inner-blocks-wrap{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-c5586b9c{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-61226197{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-61226197 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-61226197{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/04\/external-sync-camera-2x-1.webp);background-clip: padding-box;flex-wrap: wrap;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5487f77b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5487f77b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-5487f77b{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d0d3b0df{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d0d3b0df > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-d0d3b0df.uagb-layout-grid > .uagb-container-inner-blocks-wrap{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-d0d3b0df{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-573db6ef{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-573db6ef > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-573db6ef{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d9da6336{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d9da6336 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-d9da6336{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/04\/active-passive-2x.webp);background-clip: padding-box;flex-wrap: wrap;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9ee31919{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9ee31919 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-9ee31919.uagb-layout-grid > .uagb-container-inner-blocks-wrap{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-9ee31919{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a0f51320{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a0f51320 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-a0f51320{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/04\/mix-and-match-cameras-2x-800x450-1.webp);background-clip: padding-box;flex-wrap: wrap;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3a3cf7db{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3a3cf7db > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-3a3cf7db{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ad6b2a76{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ad6b2a76 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-ad6b2a76.uagb-layout-grid > .uagb-container-inner-blocks-wrap{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-ad6b2a76{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2e04eb07{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2e04eb07 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-2e04eb07{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-50af0eb4{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-50af0eb4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.wp-block-uagb-container.uagb-block-50af0eb4{flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-50af0eb4{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-cd025ccc{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-cd025ccc > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-cd025ccc.uagb-layout-grid > .uagb-container-inner-blocks-wrap{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-cd025ccc{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-faaef517{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-faaef517 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.wp-block-uagb-container.uagb-block-faaef517{flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-faaef517{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2946affe{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2946affe > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-2946affe{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.uagb-block-9fda86f2.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-9fda86f2.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-867181e8.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: none;border-color: #333;}.wp-block-uagb-buttons .uagb-block-867181e8 .uagb-buttons-repeater.wp-block-button__link{border-style: none;border-color: #333;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-46e52077{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-46e52077 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-46e52077{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-03d0b952{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-03d0b952 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-03d0b952{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8bfd2a35{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8bfd2a35 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-8bfd2a35{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c2a6af6f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c2a6af6f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-c2a6af6f{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9ad863ad{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9ad863ad > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-9ad863ad{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-03e85a84{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-03e85a84 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-03e85a84{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-33209cc4{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-33209cc4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-33209cc4{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5f32531b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5f32531b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-5f32531b{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-09341d66{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-09341d66 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-09341d66{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c98f029a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c98f029a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-c98f029a{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-5);;flex-wrap: wrap;}.uagb-block-15fc2204.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-15fc2204.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-15fc2204 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-15fc2204 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-15fc2204.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-15fc2204 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-15fc2204 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-15fc2204 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-15fc2204.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-15fc2204.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ae569a76{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ae569a76 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-ae569a76{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d119f077{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d119f077 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-d119f077{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-5);;flex-wrap: wrap;}.uagb-block-4482f584.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-4482f584.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-4482f584 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-4482f584 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-4482f584.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-4482f584 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-4482f584 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-4482f584 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-4482f584.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-4482f584.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-81d10344{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-81d10344 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-81d10344{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e6f7e635{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e6f7e635 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-e6f7e635{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5ed88e67{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5ed88e67 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-5ed88e67{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-5c866cf4.uagb-loop-container{flex-direction: column;gap: 32px;}.uagb-block-5c866cf4.uagb-loop-container > .uagb-loop-post{width: 100%;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0a6d8384{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-0a6d8384{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-5);;align-items: flex-start;justify-content: flex-start;flex-wrap: wrap;}.uagb-block-157e55c8.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 1200px;height: auto;}.uagb-block-0f1b5f2d.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.uagb-block-0f1b5f2d.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-d6ad2265.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;}.wp-block-uagb-buttons .uagb-block-d6ad2265 .uagb-buttons-repeater.wp-block-button__link{border-style: solid;}}.uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}.wp-block-uagb-advanced-heading.uagb-block-87065d6f.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-87065d6f.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-87065d6f.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-87065d6f.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.uagb-block-9f9cf29b.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-9f9cf29b.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.wp-block-uagb-buttons .uagb-block-38cab655 .uagb-button__wrapper .uagb-buttons-repeater{color: #ffffff;}.wp-block-uagb-buttons .uagb-block-38cab655 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-38cab655 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-38cab655 .uagb-buttons-repeater.wp-block-button__link{border-top-left-radius: 15px;border-top-right-radius: 15px;border-bottom-left-radius: 15px;border-bottom-right-radius: 15px;border-color: #333;border-style: none;}.wp-block-uagb-buttons .uagb-block-38cab655 .uagb-buttons-repeater.wp-block-button__link:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-38cab655 .uagb-buttons-repeater.wp-block-button__link:focus{border-color: #333;}.wp-block-uagb-buttons .uagb-block-38cab655.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-top-left-radius: 15px;border-top-right-radius: 15px;border-bottom-left-radius: 15px;border-bottom-right-radius: 15px;border-color: #333;border-style: none;}.wp-block-uagb-buttons .uagb-block-38cab655.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-38cab655 .uagb-buttons-repeater .uagb-button__link{color: #ffffff;}.wp-block-uagb-buttons .uagb-block-38cab655 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: #ffffff;}.wp-block-uagb-buttons .uagb-block-38cab655 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-38cab655 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-buttons .uagb-block-38cab655 .uagb-button__link{text-transform: normal;text-decoration: none;}@media only screen and (max-width: 976px) {.uagb-block-9f9cf29b.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-9f9cf29b.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-38cab655.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: none;border-color: #333;}.wp-block-uagb-buttons .uagb-block-38cab655 .uagb-buttons-repeater.wp-block-button__link{border-style: none;border-color: #333;}}@media only screen and (max-width: 767px) {.uagb-block-9f9cf29b.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-9f9cf29b.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-38cab655.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: none;border-color: #333;}.wp-block-uagb-buttons .uagb-block-38cab655 .uagb-buttons-repeater.wp-block-button__link{border-style: none;border-color: #333;}}.wp-block-uagb-advanced-heading.uagb-block-04d73ded.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-04d73ded.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-04d73ded.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-04d73ded.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.uagb-block-416305a8.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-416305a8.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.wp-block-uagb-buttons .uagb-block-da142d88 .uagb-button__wrapper .uagb-buttons-repeater{color: #ffffff;}.wp-block-uagb-buttons .uagb-block-da142d88 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-da142d88 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-da142d88 .uagb-buttons-repeater.wp-block-button__link{border-top-left-radius: 15px;border-top-right-radius: 15px;border-bottom-left-radius: 15px;border-bottom-right-radius: 15px;border-color: #333;border-style: none;}.wp-block-uagb-buttons .uagb-block-da142d88 .uagb-buttons-repeater.wp-block-button__link:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-da142d88 .uagb-buttons-repeater.wp-block-button__link:focus{border-color: #333;}.wp-block-uagb-buttons .uagb-block-da142d88.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-top-left-radius: 15px;border-top-right-radius: 15px;border-bottom-left-radius: 15px;border-bottom-right-radius: 15px;border-color: #333;border-style: none;}.wp-block-uagb-buttons .uagb-block-da142d88.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-da142d88 .uagb-buttons-repeater .uagb-button__link{color: #ffffff;}.wp-block-uagb-buttons .uagb-block-da142d88 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: #ffffff;}.wp-block-uagb-buttons .uagb-block-da142d88 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-da142d88 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-buttons .uagb-block-da142d88 .uagb-button__link{text-transform: normal;text-decoration: none;}@media only screen and (max-width: 976px) {.uagb-block-416305a8.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-416305a8.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-da142d88.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: none;border-color: #333;}.wp-block-uagb-buttons .uagb-block-da142d88 .uagb-buttons-repeater.wp-block-button__link{border-style: none;border-color: #333;}}@media only screen and (max-width: 767px) {.uagb-block-416305a8.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-416305a8.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-da142d88.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: none;border-color: #333;}.wp-block-uagb-buttons .uagb-block-da142d88 .uagb-buttons-repeater.wp-block-button__link{border-style: none;border-color: #333;}}.wp-block-uagb-advanced-heading.uagb-block-90475afc.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-90475afc.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-90475afc.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-90475afc.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}\";s:2:\"js\";s:9845:\"document.addEventListener(\"DOMContentLoaded\", function(){ \twindow.addEventListener(\"load\", function(){\n\t\tUAGBBlockPositioning.init( {\"block_id\":\"c37632dd\",\"directionDesktop\":\"row\",\"backgroundType\":\"color\",\"backgroundColor\":\"var(--ast-global-color-4)\",\"variationSelected\":true,\"isBlockRootParent\":true,\"layout\":\"flex\",\"gridColumnDesktop\":[{\"default\":\"custom\",\"min\":{\"unit\":\"px\",\"value\":10},\"max\":{\"unit\":\"fr\",\"value\":1},\"custom\":{\"unit\":\"fr\",\"value\":1}},{\"default\":\"custom\",\"min\":{\"unit\":\"px\",\"value\":10},\"max\":{\"unit\":\"fr\",\"value\":1},\"custom\":{\"unit\":\"fr\",\"value\":1}}],\"gridColumnTablet\":[{\"default\":\"custom\",\"min\":{\"unit\":\"px\",\"value\":10},\"max\":{\"unit\":\"fr\",\"value\":1},\"custom\":{\"unit\":\"fr\",\"value\":1}},{\"default\":\"custom\",\"min\":{\"unit\":\"px\",\"value\":10},\"max\":{\"unit\":\"fr\",\"value\":1},\"custom\":{\"unit\":\"fr\",\"value\":1}}],\"UAGPosition\":\"sticky\",\"widthDesktop\":100,\"widthTablet\":\"\",\"widthMobile\":100,\"widthType\":\"%\",\"minHeightDesktop\":\"\",\"minHeightTablet\":\"\",\"minHeightMobile\":\"\",\"minHeightType\":\"px\",\"minHeightTypeTablet\":\"px\",\"minHeightTypeMobile\":\"px\",\"directionTablet\":\"\",\"directionMobile\":\"\",\"alignItemsDesktop\":\"center\",\"alignItemsTablet\":\"\",\"alignItemsMobile\":\"\",\"justifyContentDesktop\":\"center\",\"justifyContentTablet\":\"\",\"justifyContentMobile\":\"\",\"wrapDesktop\":\"nowrap\",\"wrapTablet\":\"\",\"wrapMobile\":\"wrap\",\"alignContentDesktop\":\"\",\"alignContentTablet\":\"\",\"alignContentMobile\":\"\",\"backgroundImageDesktop\":\"\",\"backgroundImageTablet\":\"\",\"backgroundImageMobile\":\"\",\"backgroundPositionDesktop\":{\"x\":0.5,\"y\":0.5},\"backgroundPositionTablet\":\"\",\"backgroundPositionMobile\":\"\",\"backgroundSizeDesktop\":\"cover\",\"backgroundSizeTablet\":\"\",\"backgroundSizeMobile\":\"\",\"backgroundRepeatDesktop\":\"no-repeat\",\"backgroundRepeatTablet\":\"\",\"backgroundRepeatMobile\":\"\",\"backgroundAttachmentDesktop\":\"scroll\",\"backgroundAttachmentTablet\":\"\",\"backgroundAttachmentMobile\":\"\",\"backgroundOpacity\":\"\",\"backgroundImageColor\":\"#FFFFFF75\",\"gradientValue\":\"linear-gradient(90deg, rgba(6, 147, 227, 0.5) 0%, rgba(155, 81, 224, 0.5) 100%)\",\"boxShadowColor\":\"#00000070\",\"boxShadowHOffset\":0,\"boxShadowVOffset\":0,\"boxShadowBlur\":\"\",\"boxShadowSpread\":\"\",\"boxShadowPosition\":\"outset\",\"boxShadowColorHover\":\"\",\"boxShadowHOffsetHover\":0,\"boxShadowVOffsetHover\":0,\"boxShadowBlurHover\":\"\",\"boxShadowSpreadHover\":\"\",\"boxShadowPositionHover\":\"outset\",\"topPaddingDesktop\":\"10\",\"bottomPaddingDesktop\":\"10\",\"leftPaddingDesktop\":\"10\",\"rightPaddingDesktop\":\"10\",\"topPaddingTablet\":\"\",\"bottomPaddingTablet\":\"\",\"leftPaddingTablet\":\"\",\"rightPaddingTablet\":\"\",\"topPaddingMobile\":\"\",\"bottomPaddingMobile\":\"\",\"leftPaddingMobile\":\"\",\"rightPaddingMobile\":\"\",\"paddingType\":\"px\",\"paddingTypeTablet\":\"px\",\"paddingTypeMobile\":\"px\",\"paddingLink\":true,\"topMarginDesktop\":\"\",\"bottomMarginDesktop\":\"\",\"leftMarginDesktop\":\"\",\"rightMarginDesktop\":\"\",\"topMarginTablet\":\"\",\"bottomMarginTablet\":\"\",\"leftMarginTablet\":\"\",\"rightMarginTablet\":\"\",\"topMarginMobile\":\"\",\"bottomMarginMobile\":\"\",\"leftMarginMobile\":\"\",\"rightMarginMobile\":\"\",\"marginType\":\"px\",\"marginTypeTablet\":\"px\",\"marginTypeMobile\":\"px\",\"marginLink\":true,\"rowGapDesktop\":20,\"rowGapTablet\":\"\",\"rowGapMobile\":\"\",\"rowGapType\":\"px\",\"rowGapTypeTablet\":\"px\",\"rowGapTypeMobile\":\"px\",\"columnGapDesktop\":20,\"columnGapTablet\":\"\",\"columnGapMobile\":\"\",\"columnGapType\":\"px\",\"columnGapTypeTablet\":\"px\",\"columnGapTypeMobile\":\"px\",\"contentWidth\":\"alignfull\",\"innerContentWidth\":\"alignwide\",\"innerContentCustomWidthDesktop\":1200,\"innerContentCustomWidthTablet\":1024,\"innerContentCustomWidthMobile\":767,\"innerContentCustomWidthType\":\"px\",\"innerContentCustomWidthTypeTablet\":\"px\",\"innerContentCustomWidthTypeMobile\":\"px\",\"bottomType\":\"none\",\"bottomColor\":\"#333\",\"bottomHeight\":\"\",\"bottomHeightTablet\":\"\",\"bottomHeightMobile\":\"\",\"bottomWidth\":100,\"topType\":\"none\",\"topColor\":\"#333\",\"topHeight\":\"\",\"topHeightTablet\":\"\",\"topHeightMobile\":\"\",\"topWidth\":100,\"topFlip\":false,\"bottomFlip\":false,\"topContentAboveShape\":false,\"bottomContentAboveShape\":false,\"backgroundCustomSizeDesktop\":100,\"backgroundCustomSizeTablet\":\"\",\"backgroundCustomSizeMobile\":\"\",\"backgroundCustomSizeType\":\"%\",\"overlayType\":\"none\",\"overlayOpacity\":1,\"overlayBlendMode\":\"normal\",\"overlayBlendModeTablet\":\"\",\"overlayBlendModeMobile\":\"\",\"customPosition\":\"default\",\"centralizedPosition\":false,\"xPositionDesktop\":\"\",\"xPositionTablet\":\"\",\"xPositionMobile\":\"\",\"xPositionType\":\"px\",\"xPositionTypeTablet\":\"px\",\"xPositionTypeMobile\":\"px\",\"yPositionDesktop\":\"\",\"yPositionTablet\":\"\",\"yPositionMobile\":\"\",\"yPositionType\":\"px\",\"yPositionTypeTablet\":\"px\",\"yPositionTypeMobile\":\"px\",\"backgroundVideoColor\":\"#FFFFFF75\",\"backgroundVideo\":\"\",\"backgroundVideoOpacity\":\"\",\"topInvert\":false,\"bottomInvert\":false,\"textColor\":\"\",\"linkColor\":\"\",\"linkHoverColor\":\"\",\"widthTypeTablet\":\"%\",\"widthTypeMobile\":\"%\",\"overflow\":\"visible\",\"equalHeight\":false,\"gradientColor1\":\"#06558a\",\"gradientColor2\":\"#0063A1\",\"gradientType\":\"linear\",\"gradientLocation1\":0,\"gradientLocationTablet1\":\"\",\"gradientLocationMobile1\":\"\",\"gradientLocation2\":100,\"gradientLocationTablet2\":\"\",\"gradientLocationMobile2\":\"\",\"gradientAngle\":0,\"gradientAngleTablet\":\"\",\"gradientAngleMobile\":\"\",\"selectGradient\":\"basic\",\"backgroundOverlayType\":\"none\",\"backgroundOverlayImageDesktop\":\"\",\"backgroundOverlayImageTablet\":\"\",\"backgroundOverlayImageMobile\":\"\",\"backgroundPositionOverlayDesktop\":{\"x\":0.5,\"y\":0.5},\"backgroundPositionOverlayTablet\":\"\",\"backgroundPositionOverlayMobile\":\"\",\"backgroundSizeOverlayDesktop\":\"cover\",\"backgroundSizeOverlayTablet\":\"\",\"backgroundSizeOverlayMobile\":\"\",\"backgroundRepeatOverlayDesktop\":\"no-repeat\",\"backgroundRepeatOverlayTablet\":\"\",\"backgroundRepeatOverlayMobile\":\"\",\"backgroundAttachmentOverlayDesktop\":\"scroll\",\"backgroundAttachmentOverlayTablet\":\"\",\"backgroundAttachmentOverlayMobile\":\"\",\"backgroundOverlayOpacity\":1,\"backgroundOverlayColor\":\"#FFFFFF75\",\"backgroundImageOverlayColor\":\"#FFFFFF75\",\"backgroundCustomSizeOverlayDesktop\":100,\"backgroundCustomSizeOverlayTablet\":\"\",\"backgroundCustomSizeOverlayMobile\":\"\",\"backgroundCustomOverlaySizeType\":\"%\",\"customOverlayPosition\":\"default\",\"xPositionOverlayDesktop\":\"\",\"xPositionOverlayTablet\":\"\",\"xPositionOverlayMobile\":\"\",\"xPositionOverlayType\":\"px\",\"xPositionOverlayTypeTablet\":\"px\",\"xPositionOverlayTypeMobile\":\"px\",\"yPositionOverlayDesktop\":\"\",\"yPositionOverlayTablet\":\"\",\"yPositionOverlayMobile\":\"\",\"yPositionOverlayType\":\"px\",\"yPositionOverlayTypeTablet\":\"px\",\"yPositionOverlayTypeMobile\":\"px\",\"gradientOverlayColor1\":\"#06558a\",\"gradientOverlayColor2\":\"#0063A1\",\"gradientOverlayType\":\"linear\",\"gradientOverlayLocation1\":0,\"gradientOverlayLocationTablet1\":\"\",\"gradientOverlayLocationMobile1\":\"\",\"gradientOverlayLocation2\":100,\"gradientOverlayLocationTablet2\":\"\",\"gradientOverlayLocationMobile2\":\"\",\"gradientOverlayAngle\":0,\"gradientOverlayAngleTablet\":\"\",\"gradientOverlayAngleMobile\":\"\",\"selectOverlayGradient\":\"basic\",\"backgroundVideoFallbackImage\":\"\",\"globalBlockStyleName\":\"\",\"globalBlockStyleId\":\"\",\"childrenWidthDesktop\":\"\",\"childrenWidthTablet\":\"\",\"childrenWidthMobile\":\"\",\"gridColumnMobile\":[{\"default\":\"custom\",\"min\":{\"unit\":\"px\",\"value\":10},\"max\":{\"unit\":\"fr\",\"value\":1},\"custom\":{\"unit\":\"fr\",\"value\":1}}],\"gridRowDesktop\":[{\"default\":\"custom\",\"min\":{\"unit\":\"px\",\"value\":10},\"max\":{\"unit\":\"fr\",\"value\":1},\"custom\":{\"unit\":\"fr\",\"value\":1}}],\"gridRowTablet\":[{\"default\":\"custom\",\"min\":{\"unit\":\"px\",\"value\":10},\"max\":{\"unit\":\"fr\",\"value\":1},\"custom\":{\"unit\":\"fr\",\"value\":1}}],\"gridRowMobile\":[{\"default\":\"custom\",\"min\":{\"unit\":\"px\",\"value\":10},\"max\":{\"unit\":\"fr\",\"value\":1},\"custom\":{\"unit\":\"fr\",\"value\":1}}],\"gridAlignItemsDesktop\":\"stretch\",\"gridAlignItemsTablet\":\"stretch\",\"gridAlignItemsMobile\":\"stretch\",\"gridJustifyItemsDesktop\":\"stretch\",\"gridJustifyItemsTablet\":\"stretch\",\"gridJustifyItemsMobile\":\"stretch\",\"gridAlignContentDesktop\":\"stretch\",\"gridAlignContentTablet\":\"stretch\",\"gridAlignContentMobile\":\"stretch\",\"gridJustifyContentDesktop\":\"stretch\",\"gridJustifyContentTablet\":\"stretch\",\"gridJustifyContentMobile\":\"stretch\",\"orderDesktop\":\"initial\",\"orderTablet\":\"initial\",\"orderMobile\":\"initial\",\"customOrderDesktop\":\"\",\"customOrderTablet\":\"\",\"customOrderMobile\":\"\",\"containerBorderTopWidth\":\"\",\"containerBorderLeftWidth\":\"\",\"containerBorderRightWidth\":\"\",\"containerBorderBottomWidth\":\"\",\"containerBorderTopLeftRadius\":\"\",\"containerBorderTopRightRadius\":\"\",\"containerBorderBottomLeftRadius\":\"\",\"containerBorderBottomRightRadius\":\"\",\"containerBorderRadiusUnit\":\"px\",\"containerBorderTopWidthTablet\":\"\",\"containerBorderLeftWidthTablet\":\"\",\"containerBorderRightWidthTablet\":\"\",\"containerBorderBottomWidthTablet\":\"\",\"containerBorderTopLeftRadiusTablet\":\"\",\"containerBorderTopRightRadiusTablet\":\"\",\"containerBorderBottomLeftRadiusTablet\":\"\",\"containerBorderBottomRightRadiusTablet\":\"\",\"containerBorderRadiusUnitTablet\":\"px\",\"containerBorderTopWidthMobile\":\"\",\"containerBorderLeftWidthMobile\":\"\",\"containerBorderRightWidthMobile\":\"\",\"containerBorderBottomWidthMobile\":\"\",\"containerBorderTopLeftRadiusMobile\":\"\",\"containerBorderTopRightRadiusMobile\":\"\",\"containerBorderBottomLeftRadiusMobile\":\"\",\"containerBorderBottomRightRadiusMobile\":\"\",\"containerBorderRadiusUnitMobile\":\"px\",\"containerBorderStyle\":\"\",\"containerBorderColor\":\"\",\"containerBorderHColor\":\"\",\"UAGStickyLocation\":\"top\",\"UAGStickyRestricted\":false,\"UAGStickyOffset\":0}, \".uagb-block-c37632dd\" );\n\t});\n\twindow.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-6c86d97c' );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-8368e105' );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-867181e8' );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-d6ad2265' );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-38cab655' );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-da142d88' );\n});\n });\";s:18:\"current_block_list\";a:24:{i:0;s:14:\"uagb\/container\";i:2;s:21:\"uagb\/advanced-heading\";i:4;s:12:\"uagb\/buttons\";i:5;s:18:\"uagb\/buttons-child\";i:8;s:13:\"uagb\/info-box\";i:9;s:11:\"core\/spacer\";i:10;s:14:\"core\/paragraph\";i:11;s:8:\"uagb\/faq\";i:12;s:14:\"uagb\/faq-child\";i:14;s:10:\"core\/table\";i:15;s:17:\"uagb\/loop-builder\";i:16;s:17:\"uagb\/loop-wrapper\";i:18;s:10:\"uagb\/image\";i:20;s:12:\"core\/columns\";i:21;s:11:\"core\/column\";i:22;s:11:\"core\/search\";i:23;s:10:\"core\/group\";i:24;s:12:\"core\/heading\";i:25;s:17:\"core\/latest-posts\";i:26;s:20:\"core\/latest-comments\";i:27;s:13:\"core\/archives\";i:28;s:15:\"core\/categories\";i:29;s:12:\"core\/buttons\";i:30;s:11:\"core\/button\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1784120744\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:1;}"]},"uagb_featured_image_src":{"full":["https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/04\/primex22-pricing-1-800x759-2.webp",800,759,false],"thumbnail":["https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/04\/primex22-pricing-1-800x759-2-200x200.webp",200,200,true],"medium":["https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/04\/primex22-pricing-1-800x759-2-400x380.webp",400,380,true],"medium_large":["https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/04\/primex22-pricing-1-800x759-2-768x729.webp",768,729,true],"large":["https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/04\/primex22-pricing-1-800x759-2.webp",800,759,false],"1536x1536":["https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/04\/primex22-pricing-1-800x759-2.webp",800,759,false],"2048x2048":["https:\/\/www.est-kl.com\/wp-content\/uploads\/2026\/04\/primex22-pricing-1-800x759-2.webp",800,759,false]},"uagb_author_info":{"display_name":"ESTadmin14","author_link":"https:\/\/www.est-kl.com\/es\/author\/estadmin14\/"},"uagb_comment_info":0,"uagb_excerpt":"The perfect blend of range, speed, and FOV. Edge-to-edge coverage while delivering stunning camera-to-marker range and 3D accuracy.","_links":{"self":[{"href":"https:\/\/www.est-kl.com\/es\/wp-json\/wp\/v2\/posts\/10872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.est-kl.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.est-kl.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.est-kl.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.est-kl.com\/es\/wp-json\/wp\/v2\/comments?post=10872"}],"version-history":[{"count":15,"href":"https:\/\/www.est-kl.com\/es\/wp-json\/wp\/v2\/posts\/10872\/revisions"}],"predecessor-version":[{"id":23341,"href":"https:\/\/www.est-kl.com\/es\/wp-json\/wp\/v2\/posts\/10872\/revisions\/23341"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.est-kl.com\/es\/wp-json\/wp\/v2\/media\/14073"}],"wp:attachment":[{"href":"https:\/\/www.est-kl.com\/es\/wp-json\/wp\/v2\/media?parent=10872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.est-kl.com\/es\/wp-json\/wp\/v2\/categories?post=10872"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.est-kl.com\/es\/wp-json\/wp\/v2\/tags?post=10872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}